{"id":5432,"date":"2016-04-24T20:06:22","date_gmt":"2016-04-24T18:06:22","guid":{"rendered":"http:\/\/www.lamennais.org\/?p=5432&#038;lang=es"},"modified":"2020-05-30T10:12:49","modified_gmt":"2020-05-30T08:12:49","slug":"casa-generalicia-los-servicios","status":"publish","type":"post","link":"https:\/\/www.lamennais.org\/es\/casa-generalicia-los-servicios\/","title":{"rendered":"Casa Generalicia &#8211; Los servicios"},"content":{"rendered":"<h4><strong>El Superior General y su Consejo<\/strong><\/h4>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-16314 alignright\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-300x200.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-768x512.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-1024x683.jpg 1024w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-260x173.jpg 260w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-1200x800.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>El <a href=\"\/?p=5407&amp;lang=es\">Superior general y su Consejo<\/a> residen en Roma, a parte de sus per\u00edodos de visita a las Provincias y Viceprovincias de la Congregaci\u00f3n.<\/p>\n<p>El Consejo se re\u00fane al completo tres veces al a\u00f1o, en febrero-marzo, en mayo-junio y en septiembre-octubre para los tres encuentros anuales. Los Hermanos \u00abpermanentes\u00bb les acogen con alegr\u00eda y les solicitan informaci\u00f3n sobre las provincias visitadas.<\/p>\n<hr \/>\n<h4>El Secretario General y Procurador ante la Santa Sede<\/h4>\n<p>Al Secretario general le corresponde redactar las Actas de las sesiones del Consejo, responder a las diversas solicitudes del Hermano Superior General y de sus Asistentes, resolver las numerosas cuestiones materiales que se refieren a los viajes, visados y, como Procurador, intervenir ante la Santa Sede para los indultos y autorizaciones necesarias o dar los informes requeridos.<\/p>\n<hr \/>\n<h4>El Administrador General.<\/h4>\n<p>Su responsabilidad directa es : llevar las cuentas de la Administraci\u00f3n general, verificar los resultados financieros de las Provincias y presentarlos al Consejo general, y ayudar eventualmente a los Hermanos Administradores provinciales.<\/p>\n<hr \/>\n<h4>El Archivero General.<\/h4>\n<p>Cuida del buen orden y catalogaci\u00f3n de los archivos de la Congregaci\u00f3n, recibe y clasifica los documentos nuevos, responde a las solicitudes de los investigadores o de cohermanos en busca de diversas informaciones.<\/p>\n<p>Unas obras recientes en los Archivos han hecho posible la acomodaci\u00f3n de dos salas climatizadas exclusivas para la conservaci\u00f3n de los documentos m\u00e1s fr\u00e1giles o m\u00e1s confidenciales.<\/p>\n<p>Para un buen archivero, el conocimiento de los dossiers es un trabajo de larga duraci\u00f3n que necesita numerosas lecturas de los documentos archivados.<\/p>\n<p>&#8211; <a href=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2016\/04\/catgen_archives.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Catalogue General Archives FICP<\/a>\u00a0(pdf \u2013 1,11 MB)<br \/>\n&#8211;\u00a0<a href=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2016\/04\/contenu_archives.pdf\">Le contenu de nos Archives<\/a>\u00a0(pdf &#8211; 38,6 KB)<br \/>\n&#8211;\u00a0<a href=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2016\/04\/reglement_archives.pdf\">Reglement des archives<\/a>\u00a0(pdf &#8211; 34,2 KB)<\/p>\n<p>Las posibilidades ofrecidas por la inform\u00e1tica a los archiveros son estupendas : catalogar los dossiers y cada documento, numerarlos, descifrar los textos manuscritos y entenderlos al hacer el procesamiento de texto, introducir la lista de los Hermanos en la base de datos y asegurar la continua puesta al d\u00eda, tantas ocupaciones para cohermanos en retiro laboral y sobre todo para un adjunto que est\u00e1 siempre bien dispuesto, debe unir a unas s\u00f3lidas competencias t\u00e9cnicas, la paciencia legendaria de un benedictino.<\/p>\n<hr \/>\n<h4>El\u00a0Postulador General ante la Santa Sede<\/h4>\n<p>La <strong>Causa de Beatificaci\u00f3n de Juan Mar\u00eda Robert de la Mennais<\/strong> fue introducida en 1897 y la fase activa del proceso se cerr\u00f3 en 1966 con el reconocimiento romano de la Heroicidad de las virtudes. S\u00f3lo falta la comprobaci\u00f3n oficial de un milagro.<\/p>\n<p>Este trabajo supone la formaci\u00f3n de un dossier minucioso cuando llegan casos de curaciones inexplicables atribuidas al Siervo de Dios : \u00e9sta es la actual y principal funci\u00f3n del Postulador. En el pasado hemos tenido numerosos dossiers abiertos que no han prosperado. Un caso serio muy reciente est\u00e1 siendo estudiado por los m\u00e9dicos y los te\u00f3logos.<\/p>\n<p>El medio informativo del Postulador es un bolet\u00edn mensual destinado a animar la <a href=\"https:\/\/www.lamennais.org\/es\/document\/novena-menesiana\/?lang=es\">Novena mensual<\/a> en las comunidades y colegios.<\/p>\n<hr \/>\n<h4>El servicio de traducci\u00f3n<\/h4>\n<p>Este servicio es importante en la Casa. Adem\u00e1s de la ayuda de Hermanos en la congregaci\u00f3n para este servicio, varios Hermanos de la Casa dedican mucho tiempo a la traducci\u00f3n de las publicaciones y otros documentos del Consejo General, as\u00ed como la revista <a href=\"https:\/\/www.lamennais.org\/document\/la-mennais-magazine\/?lang=es\">La Mennais Magazine<\/a>.<\/p>\n<hr \/>\n<h4>El servicio de acogida<\/h4>\n<p>Funci\u00f3n necesaria e indispensable y que requiere una buena cultura ling\u00fc\u00edstica, unida a un gran sentido de acogida y de disponibilidad. La Casa Generalicia debe estar abierta a las familias y a los amigos de los Hermanos, y a otros laicos Menesianos.<\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>El Superior General y su Consejo El Superior general y su Consejo residen en Roma, a parte de sus per\u00edodos de visita a las Provincias y Viceprovincias de la Congregaci\u00f3n. El Consejo se re\u00fane al completo tres veces al a\u00f1o, en febrero-marzo, en mayo-junio y en septiembre-octubre para los tres encuentros anuales. Los Hermanos \u00abpermanentes\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[214,206],"tags":[],"class_list":["post-5432","post","type-post","status-publish","format-standard","hentry","category-casa-generalicia","category-hermanos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa Generalicia - Los servicios - LaMennais.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa Generalicia - Los servicios - LaMennais.org\" \/>\n<meta property=\"og:description\" content=\"El Superior General y su Consejo El Superior general y su Consejo residen en Roma, a parte de sus per\u00edodos de visita a las Provincias y Viceprovincias de la Congregaci\u00f3n. El Consejo se re\u00fane al completo tres veces al a\u00f1o, en febrero-marzo, en mayo-junio y en septiembre-octubre para los tres encuentros anuales. Los Hermanos \u00abpermanentes\u00bb [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es\" \/>\n<meta property=\"og:site_name\" content=\"LaMennais.org\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-24T18:06:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-30T08:12:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-300x200.jpg\" \/>\n<meta name=\"author\" content=\"admon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es\"},\"author\":{\"name\":\"admon\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/a0284cbd3544e52f538d69e4acf1e58a\"},\"headline\":\"Casa Generalicia &#8211; Los servicios\",\"datePublished\":\"2016-04-24T18:06:22+00:00\",\"dateModified\":\"2020-05-30T08:12:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es\"},\"wordCount\":613,\"image\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/P1020227-300x200.jpg\",\"articleSection\":[\"Casa Generalicia\",\"Hermanos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es\",\"name\":\"Casa Generalicia - Los servicios - LaMennais.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/P1020227-300x200.jpg\",\"datePublished\":\"2016-04-24T18:06:22+00:00\",\"dateModified\":\"2020-05-30T08:12:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/a0284cbd3544e52f538d69e4acf1e58a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es#primaryimage\",\"url\":\"http:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/P1020227-300x200.jpg\",\"contentUrl\":\"http:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/P1020227-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/casa-generalicia-los-servicios\\\/?lang=es#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lamennais.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa Generalicia &#8211; Los servicios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/\",\"name\":\"LaMennais.org\",\"description\":\"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lamennais.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/a0284cbd3544e52f538d69e4acf1e58a\",\"name\":\"admon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g\",\"caption\":\"admon\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa Generalicia - Los servicios - LaMennais.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es","og_locale":"es_ES","og_type":"article","og_title":"Casa Generalicia - Los servicios - LaMennais.org","og_description":"El Superior General y su Consejo El Superior general y su Consejo residen en Roma, a parte de sus per\u00edodos de visita a las Provincias y Viceprovincias de la Congregaci\u00f3n. El Consejo se re\u00fane al completo tres veces al a\u00f1o, en febrero-marzo, en mayo-junio y en septiembre-octubre para los tres encuentros anuales. Los Hermanos \u00abpermanentes\u00bb [&hellip;]","og_url":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es","og_site_name":"LaMennais.org","article_published_time":"2016-04-24T18:06:22+00:00","article_modified_time":"2020-05-30T08:12:49+00:00","og_image":[{"url":"http:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-300x200.jpg","type":"","width":"","height":""}],"author":"admon","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admon","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es#article","isPartOf":{"@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es"},"author":{"name":"admon","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/a0284cbd3544e52f538d69e4acf1e58a"},"headline":"Casa Generalicia &#8211; Los servicios","datePublished":"2016-04-24T18:06:22+00:00","dateModified":"2020-05-30T08:12:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es"},"wordCount":613,"image":{"@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es#primaryimage"},"thumbnailUrl":"http:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-300x200.jpg","articleSection":["Casa Generalicia","Hermanos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es","url":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es","name":"Casa Generalicia - Los servicios - LaMennais.org","isPartOf":{"@id":"https:\/\/www.lamennais.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es#primaryimage"},"image":{"@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es#primaryimage"},"thumbnailUrl":"http:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-300x200.jpg","datePublished":"2016-04-24T18:06:22+00:00","dateModified":"2020-05-30T08:12:49+00:00","author":{"@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/a0284cbd3544e52f538d69e4acf1e58a"},"breadcrumb":{"@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es#primaryimage","url":"http:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-300x200.jpg","contentUrl":"http:\/\/www.lamennais.org\/wp-content\/uploads\/2018\/03\/P1020227-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lamennais.org\/casa-generalicia-los-servicios\/?lang=es#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lamennais.org\/"},{"@type":"ListItem","position":2,"name":"Casa Generalicia &#8211; Los servicios"}]},{"@type":"WebSite","@id":"https:\/\/www.lamennais.org\/#website","url":"https:\/\/www.lamennais.org\/","name":"LaMennais.org","description":"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lamennais.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/a0284cbd3544e52f538d69e4acf1e58a","name":"admon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g","caption":"admon"}}]}},"_links":{"self":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/5432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/comments?post=5432"}],"version-history":[{"count":9,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/5432\/revisions"}],"predecessor-version":[{"id":26167,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/5432\/revisions\/26167"}],"wp:attachment":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/media?parent=5432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/categories?post=5432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/tags?post=5432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}