{"id":28662,"date":"2021-01-06T15:22:18","date_gmt":"2021-01-06T14:22:18","guid":{"rendered":"http:\/\/www.lamennais.org\/?p=28662"},"modified":"2021-01-11T16:17:08","modified_gmt":"2021-01-11T15:17:08","slug":"un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor","status":"publish","type":"post","link":"https:\/\/www.lamennais.org\/es\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/","title":{"rendered":"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor."},"content":{"rendered":"<p><strong>Nuevo. Un libro de bolsillo sobre Juan-Mar\u00eda de la Mennais.<\/strong><\/p>\n<h4><strong>Hno. Jean-Pierre. \u00ab\u00a1No se sale indemne de un encuentro como este!<\/strong> \u00bb<\/h4>\n<p><strong>\u00a1In\u00e9dito! Juan-Mar\u00eda de la Mennais se cuenta a s\u00ed mismo por primera vez. Tom\u00f3 la pluma para releer su vida, pero m\u00e1s a\u00fan para abrir horizontes, entregar el coraz\u00f3n de su vida, su testamento. Y cuenta en este libro de bolsillo c\u00f3mo la miseria educativa ha cambiado su vida hasta el punto de transformarla radicalmente y de convertirse en Fundador. Ofreced este libro, abrid este libro, hablad de este libro: \u00a1 Es un fuego y una fuente a la vez\u00a0!<\/strong><\/p>\n<p><strong>Encuentro con el Hno. Jean-Pierre Le Rest, autor de \u00abJuan-Mar\u00eda de la Mennais &#8211; Cuaderno de bit\u00e1cora de un fundador\u00bb, que acaba de aparecer en versi\u00f3n francesa y en versi\u00f3n espa\u00f1ola. La versi\u00f3n inglesa est\u00e1 en proceso de cierre. El Hno Jean-Pierre es profesor de filosof\u00eda y animador pastoral. Ha acompa\u00f1ado a grupos de j\u00f3venes y adultos en Breta\u00f1a, Polinesia y Hait\u00ed donde se encuentra actualmente. \u00a1Preguntas directas al autor con expresiones llamativas y despeinadas!<\/strong><\/p>\n<p><strong>\u00bfEn qu\u00e9 te ha marcado este trabajo y te ha llamado la atenci\u00f3n?<\/strong><br \/>\n\u00ab\u00a0\u00a1No puedo salir ileso de un trabajo como este! Me impresion\u00f3 el realismo de Juan-Mar\u00eda de la Mennais: toma las cosas, las personas y las circunstancias como son y reacciona de manera muy concreta.<\/p>\n<p>Me ha conmovido la importancia que concede a la amistad y la perspectiva que lo habita de la vida despu\u00e9s de la muerte: la vida humana es corta y preciosa, por eso hay que llenarla de amor. A medida que escrib\u00eda estas p\u00e1ginas, me sent\u00eda llamado a m\u00e1s verdad y fidelidad a mi bautismo y a mis votos. \u00bb<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-28567\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201202_171506_407-1024x623.jpg\" alt=\"\" width=\"860\" height=\"523\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201202_171506_407-1024x623.jpg 1024w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201202_171506_407-scaled-600x365.jpg 600w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201202_171506_407-300x183.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201202_171506_407-768x467.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201202_171506_407-1536x935.jpg 1536w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201202_171506_407-2048x1246.jpg 2048w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201202_171506_407-260x158.jpg 260w\" sizes=\"(max-width: 860px) 100vw, 860px\" \/><\/p>\n<h4><strong>\u00bfC\u00f3mo puede este recorrido de vida ser fuente de alegr\u00eda hoy d\u00eda?<\/strong><\/h4>\n<p>\u00ab\u00a0Constantemente enfrentado a todo tipo de problemas, encuentra una alegr\u00eda duradera y comunicativa en la certeza de la presencia de que Dios lo ama. La experimenta como resultado de su b\u00fasqueda de la felicidad para sus hermanos y hermanas en humanidad. Tambi\u00e9n me conmovi\u00f3 su humor, especialmente en las cartas a sus amigos. \u00bb<\/p>\n<p><strong>\u00bfEn qu\u00e9 puede este recorrido de Juan Mar\u00eda de la Mennais unirse a las preocupaciones de los j\u00f3venes de hoy?<\/strong><\/p>\n<p>Juan Mar\u00eda de la Mennais conf\u00eda en los j\u00f3venes\u00a0; se atreve a enviar a las primeras escuelas a Hermanos que apenas ten\u00edan veinte a\u00f1os.<\/p>\n<p>Sabe que a los j\u00f3venes les gusta que se les proponga un ideal elevado con desaf\u00edos que afrontar. Les pide que luchen con todas sus fuerzas contra las pobrezas multiformes proponiendo medios para salir de ellas. Los invita a llevar una vida sencilla.<\/p>\n<p>Les pide que trabajen juntos, no s\u00f3lo en su propio pa\u00eds, sino tambi\u00e9n fuera de las fronteras. Quiere darles a conocer y amar a un Dios que ha tomado rostro de hombre. \u00bb<\/p>\n<p><strong>Pr\u00e1ctica. Juan Mar\u00eda de la Mennais.<\/strong> \u00abCuaderno de bit\u00e1cora de un fundador\u00bb &#8211; Libro de bolsillo de 200 p\u00e1ginas. Pedirlo al Hermano Provincial o Visitador.<\/p>\n<div id=\"attachment_28574\" style=\"width: 870px\" class=\"wp-caption alignleft\"><img decoding=\"async\" aria-describedby=\"caption-attachment-28574\" class=\"wp-image-28576 size-large\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160587-1024x604.jpg\" alt=\"\" width=\"860\" height=\"507\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160587-1024x604.jpg 1024w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160587-600x354.jpg 600w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160587-300x177.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160587-768x453.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160587-1536x906.jpg 1536w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160587-260x153.jpg 260w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160587.jpg 1718w\" sizes=\"(max-width: 860px) 100vw, 860px\" \/><p id=\"caption-attachment-28574\" class=\"wp-caption-text\"><em>De izquierda a derecha: el Hno Louis Balanant, el Hno. Jean-Pierre Le Rest y el Michel Tanguy.<\/em><\/p><\/div>\n<p>El equipo de realizaci\u00f3n de la obra ha estado compuesto por el Hno. Jean-Pierre Le Rest, autor, el Hno. Louis Balanant, encargado de las fuentes hist\u00f3ricas y Michel Tanguy, director de informaci\u00f3n. Agradecimientos al traductor en lengua espa\u00f1ola, el Hno. Mariano Guti\u00e9rrez, y en lengua inglesa: los Hnos. James Hayes y Claude Beauchesne.<\/p>\n<h4><strong>\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 <\/strong><strong>En el lanzamiento de este libro el Hermano Jean-Pierre interpela a los j\u00f3venes<\/strong><\/h4>\n<h2><strong>\u00ab\u00bfQuieres ser feliz y tener \u00e9xito en tu vida? \u00a1Comp\u00e1rtelo! \u00bb<\/strong><\/h2>\n<p><strong><img decoding=\"async\" class=\"alignleft size-full wp-image-28558\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/44613844_749671618711341_5873527455574130688_n.jpg\" alt=\"\" width=\"960\" height=\"628\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/44613844_749671618711341_5873527455574130688_n.jpg 960w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/44613844_749671618711341_5873527455574130688_n-600x393.jpg 600w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/44613844_749671618711341_5873527455574130688_n-300x196.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/44613844_749671618711341_5873527455574130688_n-768x502.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/44613844_749671618711341_5873527455574130688_n-260x170.jpg 260w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/strong><\/p>\n<p><strong>Hermano Jean-Pierre, \u00bfhas identificado 3 o 4 preguntas centrales de los j\u00f3venes de hoy que les preocupan en la construcci\u00f3n de su vida?<\/strong><\/p>\n<p>Creo que las grandes preguntas que los j\u00f3venes se plantean hoy, cuando aceptan plantearse esas cuestiones y no se apartan de ellas, son las siguientes:<\/p>\n<ul>\n<li>\u00bfQu\u00e9 mundo nos espera, en qu\u00e9 mundo nos vamos a comprometer?<\/li>\n<li>\u00bfEs posible un amor duradero?<\/li>\n<li>\u00bfEncontrar\u00e9 trabajo? Y tambi\u00e9n: \u00bfCu\u00e1nto ganar\u00e9 sin \u00abtrabajar demasiado\u00bb?<\/li>\n<li>\u00bfNo son las religiones una fuente de violencia? \u00bfQu\u00e9 diferencia hay entre creer o no?<\/li>\n<\/ul>\n<p>Hay tambi\u00e9n preguntas que no se plantean necesariamente y sobre las que podemos interpelarlos:<\/p>\n<ul>\n<li>\u00bfEstoy convencido de que puedo aportar mi contribuci\u00f3n a este mundo para que sea mejor?<\/li>\n<li>Seg\u00fan lo que yo soy, \u00bfcu\u00e1l debe ser esta aportaci\u00f3n para hacer avanzar este mundo?<\/li>\n<li>Si no me comprometo, \u00bfqui\u00e9n har\u00e1 lo que es m\u00edo?<\/li>\n<li>\u00bfMe atrevo a hacerme estas preguntas cuando reflexiono sobre mi orientaci\u00f3n?<\/li>\n<\/ul>\n<p><strong>\u00bf Cu\u00e1les son las fuentes de inspiraci\u00f3n propuestas por JM de la Mennais para crecer en una vida de joven actual ?<\/strong><\/p>\n<p>Es bueno pensar en el sentido de esta palabra <strong>inspiraci\u00f3n<\/strong>: Esta palabra evoca la respiraci\u00f3n, una respiraci\u00f3n que provoca. La respiraci\u00f3n es la vida. Se dir\u00e1 de alguien que tiene aliento. Se dir\u00e1 de un autor que est\u00e1 inspirado, que su obra tiene aliento.<\/p>\n<p>Se habla tambi\u00e9n de las <strong>inspiraciones del Esp\u00edritu Santo, <\/strong>es decir, de las sugerencias que nos hace discretamente y que son siempre del orden de la novedad. El origen de todas estas palabras es el lat\u00edn \u00abSpiritus\u00bb.<\/p>\n<p>Vemos, mirando nuestra propia vida, que algunas personas nos han arrastrado como un soplo aspirante, hacia arriba.<\/p>\n<p>\u00a1As\u00ed fue Juan Mar\u00eda de la Mennais para los Hermanos que \u00e9l lanz\u00f3 a la vida y sigue animando hoy!<\/p>\n<ul>\n<li>Propone a los j\u00f3venes que se dejen inspirar por los santos y los h\u00e9roes que han hecho y siguen haciendo avanzar el mundo. M\u00e1s que las ideas, son personas que cambian las cosas, que cambian la vida social, que inspiran el progreso.<\/li>\n<li>Nos propone que escuchemos el soplo de nuestro mundo que, en muchas zonas, puede agotarse.<\/li>\n<li>Propone a los j\u00f3venes, como el papa Francisco, que sigan a Cristo, con un seguimiento ciertamente exigente, pero que puede cambiar este mundo.<\/li>\n<\/ul>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-28564\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/Aneho-Togo-College-1024x694.jpg\" alt=\"\" width=\"860\" height=\"583\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/Aneho-Togo-College-1024x694.jpg 1024w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/Aneho-Togo-College-scaled-600x406.jpg 600w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/Aneho-Togo-College-300x203.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/Aneho-Togo-College-768x520.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/Aneho-Togo-College-1536x1041.jpg 1536w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/Aneho-Togo-College-2048x1387.jpg 2048w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/Aneho-Togo-College-260x176.jpg 260w\" sizes=\"(max-width: 860px) 100vw, 860px\" \/><\/strong><\/p>\n<p><strong>\u00bfPor qu\u00e9 JMLM puede ser un punto de apoyo para ayudar a un adolescente o a un adulto joven a construirse?<\/strong><\/p>\n<p>En primer lugar, porque era un <u>hombre como nosotros<\/u>, con una familia que no era perfecta, en un contexto socioecon\u00f3mico determinado que quer\u00eda mejorar.<\/p>\n<p>Luego, porque la narraci\u00f3n de su vida es inspiradora. Finalmente, por su <u>realismo\u00a0<\/u>; no llor\u00f3 sobre su tiempo. Lo mir\u00f3 a la cara y lo agarr\u00f3 con sus brazos. Hizo progresar de manera notable la sociedad de su tiempo mediante la educaci\u00f3n de la juventud.<\/p>\n<p><strong>Muchos j\u00f3venes buscan br\u00fajulas, puntos de referencia, faros. \u00bfC\u00f3mo puede JMLM hablarles?<\/strong><\/p>\n<p>En efecto, al escribir su cuaderno de bit\u00e1cora, Juan-Mar\u00eda record\u00f3 que, a menudo, ha hecho un balance para guiar su vida teniendo en cuenta los signos y las se\u00f1ales.<\/p>\n<p>Hay dos maneras de responder a esa pregunta. Pregunt\u00e1ndose c\u00f3mo hablar\u00eda hoy a los j\u00f3venes, o pregunt\u00e1ndose el contenido de lo que les dir\u00eda.<\/p>\n<p>Les hablar\u00eda de manera directa y sin rodeos, atrevi\u00e9ndose a hacerles preguntas que molestan y que no siempre se atreven a hacerles, quiz\u00e1s porque tienen miedo de que les miren mal.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-28570\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201208_152649-871x1024.jpg\" alt=\"\" width=\"860\" height=\"1011\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201208_152649-871x1024.jpg 871w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201208_152649-scaled-600x705.jpg 600w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201208_152649-255x300.jpg 255w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201208_152649-768x903.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201208_152649-1307x1536.jpg 1307w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201208_152649-1742x2048.jpg 1742w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/IMG_20201208_152649-260x306.jpg 260w\" sizes=\"(max-width: 860px) 100vw, 860px\" \/><\/p>\n<p>A veces dec\u00eda a los j\u00f3venes: Si os dicen claramente algunas cosas, experimentar\u00e9is a ese ciego de nacimiento que descubre de repente un mundo que no conoc\u00eda y que, por supuesto, se maravilla de \u00e9l. Y \u00e9l les dir\u00eda:<\/p>\n<ul>\n<li><strong>\u00a1Si supierais lo mucho que Dios os ama, m\u00e1s que vosotros mismos, quienquiera que se\u00e1is y lo que haya sido vuestro pasado!<\/strong><\/li>\n<li><strong>Lo que Dios ama de ti es lo que quieres ser.<\/strong><\/li>\n<li><strong>Ten\u00e9is una misi\u00f3n que cumplir en este mundo: esto es lo que da sentido a vuestra vida.<\/strong><\/li>\n<li><strong>Nada est\u00e1 escrito de antemano, \u00a1es vuestra tarea inventar vuestro camino!<\/strong><\/li>\n<li><strong>No te dejes inmovilizar ni encerrar por tus smartphones: \u00a1Vive en el mundo real!<\/strong><\/li>\n<li><strong>Encuentra la belleza del trabajo manual y si este es tu trabajo, encuentra en \u00e9l tu felicidad.<\/strong><\/li>\n<\/ul>\n<p><strong>\u00bfC\u00f3mo puede un joven desarrollar y crecer en una vida interior y\/o espiritual hoy? \u00bfEn qu\u00e9 apoyarse? \u00bfQu\u00e9 consejos?<\/strong><\/p>\n<p>Hablar de la vida interior no es contraponerla a la vida exterior. \u00a1Al contrario! Pero hay que reconocer que la sociedad actual lleva a los j\u00f3venes a vivir fuera de s\u00ed mismos. Experimentaron lo que San Agust\u00edn, contando su historia personal, dec\u00eda releyendo el per\u00edodo de su vida que fue llenado por los entretenimientos: \u00abT\u00fa estabas dentro de m\u00ed y yo estaba fuera de m\u00ed y fuera de m\u00ed te buscaba. \u00bb<\/p>\n<p>Es urgente desarrollar hoy en los j\u00f3venes <strong>el sentido de la interioridad<\/strong>. No s\u00f3lo como lo hacen todos aquellos, cada vez m\u00e1s numerosos, que buscan experimentar a trav\u00e9s del yoga y otras pr\u00e1cticas similares. En estos momentos de calma, de recogimiento, no se trata s\u00f3lo de encontrarse a s\u00ed mismo, lo que ya es algo, sino tambi\u00e9n de descubrir una presencia en lo \u00edntimo de s\u00ed mismo, la presencia de Dios.<\/p>\n<p>Las parroquias y las escuelas deben proponer a los j\u00f3venes que vivan tales experiencias. As\u00ed como los grupos donde pueden insertarse.<\/p>\n<p>No es tan dif\u00edcil ense\u00f1ar a los j\u00f3venes a orar a partir del Evangelio o a partir de textos fuertes. Pienso, por ejemplo, en el libro <em>\u00abYoucat, j\u00f3venes, oraci\u00f3n\u00bb,<\/em> que me parece notable en este sentido.<\/p>\n<p>En los numerosos retiros de ni\u00f1os que animaba, Juan Mar\u00eda de la Mennais se maravillaba de ver c\u00f3mo los ni\u00f1os eran capaces de tales experiencias de interioridad.<\/p>\n<p><strong>\u00bfC\u00f3mo puede un joven experimentar un camino de interrogaci\u00f3n -que puede convertirse en camino de fe o no- en el seno de un colegio Menesiano?<\/strong><\/p>\n<p>Para empezar, cabe recordar algunas evidencias:<\/p>\n<p>S\u00f3lo se desea lo que se conoce.<\/p>\n<ul>\n<li>La fe, como dice san Pablo, nace de la escucha de la palabra de Dios<\/li>\n<li>En el seno de una escuela menesiana, la interrogaci\u00f3n nace ante todo del ambiente reinante, trabajo serio, vida en com\u00fan, responsabilizaci\u00f3n de los j\u00f3venes, relaciones de calidad entre los educadores y los j\u00f3venes.<\/li>\n<li>El testimonio de los \u00abmaestros\u00bb es la primera fuente de interrogaci\u00f3n para los j\u00f3venes. \u00bfD\u00f3nde est\u00e1 esta preocupaci\u00f3n?<\/li>\n<li>Juan Mar\u00eda de la Mennais dif\u00edcilmente comprender\u00eda que no se anuncie expl\u00edcitamente a Jesucristo en las escuelas que pertenecen a lo que se llama precisamente la red menesiana. Nos pide que \u00abanunciemos a Jesucristo\u00bb: \u00bfPodr\u00eda la publicidad hacerlo mejor que nosotros cuando solicita a los j\u00f3venes de muchas maneras?<\/li>\n<li>Por lo tanto, se necesitan personas que se atrevan a anunciar la palabra de Dios.<\/li>\n<li>Se necesitan tiempos y lugares donde \u00e9sta pueda ser dicha y escuchada.<\/li>\n<\/ul>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-28561\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/ANEC-students-invited-to-the-feast-Oct-13-2019-San-Jose-1024x826.jpg\" alt=\"\" width=\"860\" height=\"694\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/ANEC-students-invited-to-the-feast-Oct-13-2019-San-Jose-1024x826.jpg 1024w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/ANEC-students-invited-to-the-feast-Oct-13-2019-San-Jose-600x484.jpg 600w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/ANEC-students-invited-to-the-feast-Oct-13-2019-San-Jose-300x242.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/ANEC-students-invited-to-the-feast-Oct-13-2019-San-Jose-768x619.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/ANEC-students-invited-to-the-feast-Oct-13-2019-San-Jose-260x210.jpg 260w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/ANEC-students-invited-to-the-feast-Oct-13-2019-San-Jose.jpg 1271w\" sizes=\"(max-width: 860px) 100vw, 860px\" \/><\/strong><\/p>\n<p><strong>Si JM LM tuviera que hablarle al coraz\u00f3n de un joven de hoy, \u00bfqu\u00e9 le dir\u00eda?<\/strong><\/p>\n<p>\u00c9l le dir\u00eda:<\/p>\n<ul>\n<li><strong>\u00bfQuieres ser feliz y tener \u00e9xito en tu vida? \u00a1Entr\u00e9gala, ofr\u00e9cela, comp\u00e1rtela!<\/strong> Sea cual sea tu elecci\u00f3n de vida, soltero o casado, s\u00f3lo el ego\u00edsta equivoca su vida.<\/li>\n<li><strong>No protestes contra el mundo actual si no est\u00e1s decidido a ayudar a cambiarlo.<\/strong> Estoy de acuerdo con el Papa Francisco cuando dice: \u00a1J\u00f3venes, no os qued\u00e9is en el balc\u00f3n observando lo que pasa! \u00a1Actuad!<\/li>\n<li>Aprende a amar. Si hay hoy tanta violencia, si tantas parejas se separan, es porque los seres no saben amar. <strong>Aprende a amar, es decir, a poner al otro por encima de ti.<\/strong><\/li>\n<li><strong>Sin la ayuda de Jes\u00fas, tendr\u00e1s muchas dificultades<\/strong>: lo que cuenta es el cambio de tu mirada. Es necesario que puedas mirar a cada hombre como Jes\u00fas lo mira.<\/li>\n<li><strong>Vosotros, haced ejercicio f\u00edsico<\/strong>. De lo contrario, \u00bfqu\u00e9 salud tendr\u00e1s a los 50 a\u00f1os?<\/li>\n<\/ul>\n<p><strong>Si JMLM estuviera hoy con nosotros, \u00bfqu\u00e9 vivir\u00eda?<\/strong><\/p>\n<ul>\n<li>Vivir\u00eda en la intimidad de Cristo pregunt\u00e1ndose en todo momento: \u00abJes\u00fas, si estuvieras ahora a mi lado, \u00bfqu\u00e9 har\u00edas? \u00bb<\/li>\n<li>\u00c9l interrogar\u00eda vigorosamente a los j\u00f3venes sobre lo que da la calidad a una vida: la acumulaci\u00f3n las riquezas o el sentimiento de hacer aquello para lo que uno est\u00e1 hecho?<\/li>\n<li>\u00c9l les explicar\u00eda a los j\u00f3venes el valor del trabajo manual y descubrir\u00eda su belleza.<\/li>\n<li>Se atrever\u00eda a plantear a los j\u00f3venes preguntas muy directas sobre su vocaci\u00f3n y sobre la vocaci\u00f3n a la vida consagrada: \u00ab\u00bfNo crees que Dios te llama? \u00bb<\/li>\n<li>\u00c9l entrenar\u00eda a los j\u00f3venes al servicio de los pobres de nuestro tiempo. Es una experiencia \u00fanica que abre los ojos al mundo real y conduce a relativizar sus propios problemas.<\/li>\n<\/ul>\n<p><strong>\u00bfY estar\u00eda presente y activo c\u00f3mo y con qui\u00e9n?<\/strong><\/p>\n<ul>\n<li>Estar\u00eda presente al lado de sus Hermanos, los religiosos, y los animar\u00eda a continuar su tarea de servicio.<\/li>\n<li>Apoyar\u00eda a los j\u00f3venes y adultos que comparten su proyecto educativo y les har\u00eda maravillarse ante la grandeza de su vocaci\u00f3n.<\/li>\n<li>Multiplicar\u00eda los grupos, quiz\u00e1s tambi\u00e9n por Facebook, que permitan a los j\u00f3venes encontrarse, compartir sus vidas y apoyarse mutuamente.<\/li>\n<\/ul>\n<p><strong>Tambi\u00e9n impulsar\u00eda la Ense\u00f1anza Cat\u00f3lica a profundizar, enriquecer y vivir plenamente su alma. \u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevo. Un libro de bolsillo sobre Juan-Mar\u00eda de la Mennais. Hno. Jean-Pierre. \u00ab\u00a1No se sale indemne de un encuentro como este! \u00bb \u00a1In\u00e9dito! Juan-Mar\u00eda de la Mennais se cuenta a s\u00ed mismo por primera vez. Tom\u00f3 la pluma para releer su vida, pero m\u00e1s a\u00fan para abrir horizontes, entregar el coraz\u00f3n de su vida, su [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[],"class_list":["post-28662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor. - LaMennais.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor. - LaMennais.org\" \/>\n<meta property=\"og:description\" content=\"Nuevo. Un libro de bolsillo sobre Juan-Mar\u00eda de la Mennais. Hno. Jean-Pierre. \u00ab\u00a1No se sale indemne de un encuentro como este! \u00bb \u00a1In\u00e9dito! Juan-Mar\u00eda de la Mennais se cuenta a s\u00ed mismo por primera vez. Tom\u00f3 la pluma para releer su vida, pero m\u00e1s a\u00fan para abrir horizontes, entregar el coraz\u00f3n de su vida, su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es\" \/>\n<meta property=\"og:site_name\" content=\"LaMennais.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-06T14:22:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-11T15:17:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160568.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2452\" \/>\n\t<meta property=\"og:image:height\" content=\"1734\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Herv\u00e9 Asse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Herv\u00e9 Asse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es\"},\"author\":{\"name\":\"Herv\u00e9 Asse\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\"},\"headline\":\"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor.\",\"datePublished\":\"2021-01-06T14:22:18+00:00\",\"dateModified\":\"2021-01-11T15:17:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es\"},\"wordCount\":2300,\"image\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/P1160568.jpg\",\"articleSection\":[\"NOTICIAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es\",\"name\":\"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor. - LaMennais.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/P1160568.jpg\",\"datePublished\":\"2021-01-06T14:22:18+00:00\",\"dateModified\":\"2021-01-11T15:17:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es#primaryimage\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/P1160568.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/P1160568.jpg\",\"width\":2452,\"height\":1734},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\\\/?lang=es#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lamennais.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/\",\"name\":\"LaMennais.org\",\"description\":\"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lamennais.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\",\"name\":\"Herv\u00e9 Asse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"caption\":\"Herv\u00e9 Asse\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor. - LaMennais.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es","og_locale":"es_ES","og_type":"article","og_title":"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor. - LaMennais.org","og_description":"Nuevo. Un libro de bolsillo sobre Juan-Mar\u00eda de la Mennais. Hno. Jean-Pierre. \u00ab\u00a1No se sale indemne de un encuentro como este! \u00bb \u00a1In\u00e9dito! Juan-Mar\u00eda de la Mennais se cuenta a s\u00ed mismo por primera vez. Tom\u00f3 la pluma para releer su vida, pero m\u00e1s a\u00fan para abrir horizontes, entregar el coraz\u00f3n de su vida, su [&hellip;]","og_url":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es","og_site_name":"LaMennais.org","article_published_time":"2021-01-06T14:22:18+00:00","article_modified_time":"2021-01-11T15:17:08+00:00","og_image":[{"width":2452,"height":1734,"url":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160568.jpg","type":"image\/jpeg"}],"author":"Herv\u00e9 Asse","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Herv\u00e9 Asse","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es#article","isPartOf":{"@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es"},"author":{"name":"Herv\u00e9 Asse","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844"},"headline":"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor.","datePublished":"2021-01-06T14:22:18+00:00","dateModified":"2021-01-11T15:17:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es"},"wordCount":2300,"image":{"@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es#primaryimage"},"thumbnailUrl":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160568.jpg","articleSection":["NOTICIAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es","url":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es","name":"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor. - LaMennais.org","isPartOf":{"@id":"https:\/\/www.lamennais.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es#primaryimage"},"image":{"@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es#primaryimage"},"thumbnailUrl":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160568.jpg","datePublished":"2021-01-06T14:22:18+00:00","dateModified":"2021-01-11T15:17:08+00:00","author":{"@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844"},"breadcrumb":{"@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es#primaryimage","url":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160568.jpg","contentUrl":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2021\/01\/P1160568.jpg","width":2452,"height":1734},{"@type":"BreadcrumbList","@id":"https:\/\/www.lamennais.org\/un-libro-como-fuente-ha-leido-el-cuaderno-de-bitacora-de-juan-maria-de-la-mennais-entrevista-de-cuatro-verdades-con-el-hno-jean-pierre-le-rest-su-autor\/?lang=es#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lamennais.org\/"},{"@type":"ListItem","position":2,"name":"UN LIBRO COMO FUENTE. \u00bfHa le\u00eddo el \u00abCuaderno de bit\u00e1cora de Juan Mar\u00eda de la Mennais\u00bb? Entrevista de \u00abcuatro verdades\u00bb con el Hno. Jean-Pierre Le Rest, su autor."}]},{"@type":"WebSite","@id":"https:\/\/www.lamennais.org\/#website","url":"https:\/\/www.lamennais.org\/","name":"LaMennais.org","description":"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lamennais.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844","name":"Herv\u00e9 Asse","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","caption":"Herv\u00e9 Asse"}}]}},"_links":{"self":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/28662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/comments?post=28662"}],"version-history":[{"count":2,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/28662\/revisions"}],"predecessor-version":[{"id":28664,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/28662\/revisions\/28664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/media\/28573"}],"wp:attachment":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/media?parent=28662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/categories?post=28662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/tags?post=28662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}