{"id":28415,"date":"2021-01-02T12:37:58","date_gmt":"2021-01-02T11:37:58","guid":{"rendered":"http:\/\/www.lamennais.org\/?p=28415"},"modified":"2021-07-08T13:47:43","modified_gmt":"2021-07-08T11:47:43","slug":"juin-2021","status":"publish","type":"post","link":"https:\/\/www.lamennais.org\/es\/juin-2021\/","title":{"rendered":"Juin 2021"},"content":{"rendered":"<p><strong>MOIS DE JUIN<\/strong><\/p>\n<p>Consacr\u00e9 au Coeur Sacr\u00e9 de J\u00e9sus<\/p>\n<p>Apostolat de la Pri\u00e8re, intention d\u2019\u00e9vang\u00e9lisation<\/p>\n<p>* * * * * * * *<\/p>\n<p><strong>La beaut\u00e9 du mariage&nbsp;:<\/strong> Prions pour les jeunes qui se pr\u00e9parent au mariage avec le soutien d&#8217;une communaut\u00e9 chr\u00e9tienne : qu&#8217;ils grandissent dans l&#8217;amour, avec g\u00e9n\u00e9rosit\u00e9, fid\u00e9lit\u00e9 et patience.<\/p>\n<p><a name=\"_Toc518119365\"><\/a><\/p>\n<p><strong> <a name=\"1\">1 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp; MARDI<\/a><\/strong><\/p>\n<p><a name=\"1\"><\/a><\/p>\n<p><a name=\"1\"><\/a><\/p>\n<p><a name=\"1\"><\/a><\/p>\n<p><a name=\"1\"><\/p>\n<ol start=\"165\">\n<li>Justin, philosophe et apologiste, M., \u2020 165.(3)<\/li>\n<\/ol>\n<p><strong>\u0084<\/strong><strong> Constitutions 1 a :<\/strong><\/p>\n<p>La Congr\u00e9gation des Fr\u00e8res de l&#8217;Instruction Chr\u00e9tienne de Plo\u00ebrmel est une Congr\u00e9gation la\u00efcale, de droit pontifical, fond\u00e9e par Jean-Marie de la Mennais et Gabriel Deshayes.<\/p>\n<p><strong>\u0084<\/strong><strong> Au F. Yves H\u00e9relle, le 15 mars 1833 :<\/strong><\/p>\n<p>La grande illusion des hommes, m\u00eame les plus pieux, est de chercher dans ce monde une position o\u00f9 ils n\u2019aient rien \u00e0 souffrir.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1964, F. \u00c9phrem-Pierre Morin.- 1984, F. Pierre Drouad\u00e8ne (\u00c9douard-Marie).- 1994, F. Antimo Garc\u00eda Escalada (Avelino).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"1\"><\/a><a name=\"1\"><\/a><a name=\"1\"><\/a><a name=\"1\"><\/a><a name=\"_Toc518119368\"><\/a><a name=\"_Toc518187323\"><\/a><a name=\"_Toc46533754\"><\/a><strong><a name=\"2\">2&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"_Toc518119370\"><\/a><strong>MERCREDI <\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/p>\n<ol start=\"177\">\n<li>Pothin et Ste Blandine, et leurs compagnons martyrs \u00e0 Lyon, \u2020 177.<\/li>\n<li>Marcellin et Pierre, Mm, \u2020 304.<\/li>\n<\/ol>\n<p><em>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Triduum \u00e0 Saint Joseph pour les vocations (cf. pri\u00e8re page 14).<\/em><\/p>\n<p><strong><em>Intentions<\/em><\/strong><em>&nbsp;: <\/em>&#8211; <em>Pour que de nouvelles vocations de Fr\u00e8res donnent vitalit\u00e9 \u00e0 la mission de la Congr\u00e9gation.<\/em><strong>.<\/strong><\/p>\n<p>&#8211; La communaut\u00e9 de St Charles Lwanga, Kasasa (Ouganda).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 1b :<\/strong><\/p>\n<p>La Congr\u00e9gation rassemble des hommes qui, en r\u00e9ponse \u00e0 un appel particulier de l&#8217;Esprit-Saint, se vouent totalement \u00e0 Dieu par la profession publique des voeux de chastet\u00e9, de pauvret\u00e9 et d&#8217;ob\u00e9issance, dans une vie de communion fraternelle et d&#8217;apostolat au service du peuple de Dieu, sp\u00e9cialement de la jeunesse, avec une pr\u00e9dilection pour les pauvres, par l&#8217;instruction et l&#8217;\u00e9ducation chr\u00e9tiennes.<\/p>\n<p><strong>\u0084<\/strong><strong> Aux pr\u00eatres de Saint-M\u00e9en, sermon &#8216;Le pr\u00eatre-religieux doit imiter J-C dans son d\u00e9pouillement total&#8217;&nbsp; :<\/strong><\/p>\n<p>O\u00f9 sont ceux qui ne r\u00e9servent rien avec Dieu, qui ne font pas avec lui une sorte de march\u00e9 dans lequel ils traitent au plus bas prix possible ?<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1973, F. \u00c9nos Tousignant (\u00c9loi-Joseph).- 1991, FF. Julien Belsoeur (Ludovic) et Charles-Joseph Foucaud (Jean-Gabriel Perboyre).- 2002, FF. F\u00e9lix L\u00f3pez Fern\u00e1ndez (Joaqu\u00edn-Mar\u00eda) et Albert Morin (Bertin-Joseph).- 2003, F. Jean-Baptiste Renaud (Jean-Alain).- 2013, F. Henri Ferchaux (Octavien-Louis).- 2014, F. Abraham Bajuga (Bosco Mary).<\/p>\n<p><a name=\"_Toc518119371\"><\/a><a name=\"_Toc518187324\"><\/a><a name=\"_Toc46533755\"><\/a><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><a name=\"3\">3&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"3\"><strong>JEUDI&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp; <\/strong>de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"3\"><br \/>\n<\/a><a name=\"3\"><\/a><a name=\"_Toc518119372\"><\/a>Les SS. Charles Lwanga et ses compagnons, Mm. en Ouganda, \u2020 1885-87 (3).<\/p>\n<p>Intention&nbsp;: &nbsp;Les Fr\u00e8res de l\u2019Ouganda et du Soudan du Sud, et leurs \u0153uvres.<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 2 a :<\/strong><\/p>\n<p>Par leur cons\u00e9cration religieuse, les Fr\u00e8res manifestent non seulement leur volont\u00e9 de mourir au p\u00e9ch\u00e9, mais leur renoncement \u00e0 d&#8217;authentiques valeurs humaines, pour mieux s&#8217;attacher \u00e0 J\u00e9sus Christ.<\/p>\n<p><strong>\u0084<\/strong><strong> M\u00e9morial, p. 63 :<\/strong><\/p>\n<p>L\u2019homme le plus raisonnable serait celui qui nourrirait son esprit d\u2019une seule pens\u00e9e&nbsp;: Dieu seul&nbsp;! Mais il n\u2019y a que le coeur chr\u00e9tien qui entende ces mots&nbsp;: Dieu seul.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1961, F. D\u00e9sir\u00e9-Fran\u00e7ois Le Jollec.- 1993, F. Ignacio Mar\u00eda Corta (Germ\u00e1n).- 2006, F. Alphonse Chapeau (Athanase).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119374\"><\/a><a name=\"_Toc518187325\"><\/a><a name=\"_Toc46533756\"><\/a><\/p>\n<p><strong><a name=\"4\">4&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; VENDREDI&nbsp;<\/a><\/strong><a name=\"4\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"4\"><br \/>\n<\/a><a name=\"4\"><\/a><a name=\"_Toc518119375\"><\/a>Ste Clotilde, Vve, \u2020 545.<\/p>\n<ol start=\"1608\">\n<li>Fran\u00e7ois Caracciolo, fondateur en Italie des Clercs r\u00e9guliers mineurs, \u2020&nbsp;1608.<\/li>\n<\/ol>\n<p><strong>\u0084<\/strong><strong> Constitutions 2 b :<\/strong><\/p>\n<p>L&#8217;\u00e9cole constitue le milieu privil\u00e9gi\u00e9, mais non exclusif de l\u2019activit\u00e9 apostolique des Fr\u00e8res. Fid\u00e8les aux volont\u00e9s des Fondateurs, ils visent avant tout, dans leur action \u00e9ducative, \u00e0 faire conna\u00eetre J\u00e9sus- Christ et son \u00c9vangile\u2026<\/p>\n<p><strong>\u0084<\/strong><strong> Au F. Ambroise Le Haiget, le 15 juillet 1842 :<\/strong><\/p>\n<p>Ne vous d\u00e9couragez point&nbsp;; soyez calme dans toutes vos d\u00e9marches et dans toutes vos paroles quels que soient les torts que l\u2019on ait envers vous&nbsp;: sachez souffrir en chr\u00e9tien.<\/p>\n<p>D\u00c9FUNT<\/p>\n<p>1968,&nbsp; F. Gr\u00e9goire Bernard (Bernard-\u00c9loi).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119378\"><\/a><a name=\"_Toc518187326\"><\/a><a name=\"_Toc46533757\"><\/a><\/p>\n<p><strong><a name=\"5\">5&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; SAMEDI&nbsp;&nbsp;<\/a><\/strong><a name=\"5\">&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"5\"><br \/>\n<\/a><\/p>\n<ol><a name=\"5\"><br \/>\n<\/a><\/p>\n<li><a name=\"5\"><\/a><a name=\"_Toc518119379\"><\/a> Boniface, ap\u00f4tre de l\u2019Allemagne, \u00c9v., M., \u2020 754 (3).<\/li>\n<\/ol>\n<p>(Au br\u00e9viaire, premi\u00e8res v\u00eapres de la F\u00eate du Saint-Sacrement)<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 3 :<\/strong><\/p>\n<p>L&#8217;esprit de la Congr\u00e9gation est un esprit de foi et de charit\u00e9, d&#8217;abn\u00e9gation et d&#8217;humilit\u00e9. Sa devise est \u00ab Dieu Seul\u00bb.<\/p>\n<p><strong>\u0084<\/strong><strong> Au F. Ambroise Le Haiget, le 18 mai 1832 :<\/strong><\/p>\n<p>L\u2019humilit\u00e9, la charit\u00e9, la douceur, voil\u00e0 vos armes; les reproches trop vifs ne servent qu\u2019\u00e0 irriter ceux \u00e0 qui on les adresse.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1998, F. Roland Hardy (Eug\u00e8ne-Alphonse).- &nbsp;2005, &nbsp;F. Albert Youinou. \u2013 2019, F Donatien Mbohilinie.- 2020, F. Bernard Mwebaze.<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119380\"><\/a><a name=\"_Toc518187328\"><\/a><a name=\"_Toc46533758\"><\/a><strong><a name=\"6\">6&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; DIMANCHE SAINT-SACREMENT (1)<\/a><\/strong><\/p>\n<p><a name=\"6\"><br \/>\n<\/a><\/p>\n<ol start=\"1134\"><a name=\"6\"><br \/>\n<\/a><\/p>\n<li><a name=\"6\"><\/a><a name=\"_Toc518119381\"><\/a> Norbert, \u00c9v. de Magdebourg, fondateur des Pr\u00e9montr\u00e9s, \u2020 1134.<\/li>\n<li><a name=\"_Toc518119382\"><\/a> Claude, abb\u00e9 dans le Jura, \u2020 703.<\/li>\n<li><a name=\"_Toc518119383\"><\/a> Marcellin Champagnat, fondateur des Fr\u00e8res Maristes, \u2020 1840.<\/li>\n<\/ol>\n<p>1819.- Nos Fondateurs, Jean-Marie Robert de la Mennais et Gabriel Deshayes, signent, \u00e0 Saint-Brieuc, un trait\u00e9 qui stipule la fusion de leurs deux fondations.<\/p>\n<p>1861.- D\u00e9c\u00e8s de Mgr Nicolas-Augustin de la Croix d\u2019Azolette, archev\u00eaque d\u2019Auch, Fondateur de nos Fr\u00e8res du Midi<\/p>\n<p>Intention : Les vocations sacerdotales en Occident.<\/p>\n<p>Au br\u00e9viaire, deuxi\u00e8me&nbsp; semaine.<\/p>\n<p><strong>\u0084<\/strong><strong> Directoire 151 :<\/strong><\/p>\n<p>Des sessions de formation et de r\u00e9novation sont offertes aux Fr\u00e8res au cours de leur vie religieuse. Elles visent avant tout un approfondissement de leur relation \u00e0 Dieu, dans un climat de pri\u00e8re, de r\u00e9flexion et d\u2019\u00e9tude. Elles permettent aussi une meilleure connaissance de l\u2019esprit et des \u0153uvres de la Congr\u00e9gation, favorisant ainsi l\u2019unit\u00e9 dans la diversit\u00e9 des soci\u00e9t\u00e9s et des cultures.<\/p>\n<p><strong>\u0084<\/strong><strong> Directoire de 1825 :<\/strong><\/p>\n<p>Pendant votre action de gr\u00e2ces apr\u00e8s la communion, vous \u00e9couterez en silence la voix de J\u00e9sus-Christ r\u00e9ellement pr\u00e9sent au-dedans de vous&nbsp;; vous lui exposerez vos besoins et vous lui demanderez les vertus qui vous manquent.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1973, F. \u00c9douard Delorme (Florentin).- 1987, F. Ad\u00e9lard Croteau (Eug\u00e8ne-Victor).- 1998, F. Pierre-Jean Cosquer (Euchariste).- 2003, F. Remo Andreucci (Guido-Maria).- &nbsp;2004, F. Alfred Paquin (Andr\u00e9 Avellin).- 2009, F. Pierre Lefeuvre (Dominique-Andr\u00e9).- 2011, F. Alphonse Guilloux (Alphonse-\u00c9tienne).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119384\"><\/a><a name=\"_Toc518187329\"><\/a><a name=\"_Toc46533759\"><\/a><\/p>\n<p><strong><a name=\"7\">7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; LUNDI&nbsp; &nbsp;<\/a><\/strong><a name=\"7\">&nbsp;&nbsp;&nbsp; de la f\u00e9rie<\/a><\/p>\n<p><a name=\"7\">1853.- Le P\u00e8re de La Mennais c\u00e9l\u00e8bre la premi\u00e8re messe dans la chapelle des Filles de la Providence, \u00e0 Saint-Brieuc.<\/a><\/p>\n<p><a name=\"7\">Intentions&nbsp;: &#8211; Les Filles de la Providence de Saint-Brieuc.<\/a><\/p>\n<p><a name=\"7\">&#8211; La communaut\u00e9 de Nebbi Town (Ouganda)<\/a><\/p>\n<p><a name=\"7\"><strong>\u0084<\/strong><strong> Constitutions 4 :<\/strong><\/p>\n<p>Les Fr\u00e8res professent une totale soumission \u00e0 l&#8217;\u00e9gard du Pape, leur premier Sup\u00e9rieur, en raison m\u00eame du voeu d&#8217;ob\u00e9issance, une respectueuse adh\u00e9sion aux directives des \u00e9v\u00eaques, un esprit de franche collaboration avec les pr\u00eatres, les religieux, les religieuses et les la\u00efcs.<\/p>\n<p><strong>\u0084<\/strong><strong> \u00c0 Melle Marie Jallobert de Monville, le 27 janvier 1815 :<\/strong><\/p>\n<p>Cherchez en Dieu et en Dieu seul des consolations \u00e0 vos peines&nbsp;: il ne vous d\u00e9fend pas de go\u00fbter sa joie, lorsqu\u2019il vous la donne, mais tenez plus \u00e0 lui qu\u2019\u00e0 ses dons.<\/p>\n<p>D\u00c9FUNT<\/p>\n<p>1981, F. Armand St-Onge (L\u00e9onard de Port-Maurice).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"7\"><\/a><a name=\"7\"><\/a><a name=\"7\"><\/a><a name=\"7\"><\/a><a name=\"_Toc518119387\"><\/a><a name=\"_Toc518187330\"><\/a><a name=\"_Toc46533760\"><\/a><\/p>\n<p><strong><a name=\"8\">8 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp; MARDI &nbsp;<\/a><\/strong><a name=\"8\">&nbsp;&nbsp;&nbsp; de la f\u00e9rie<\/a><\/p>\n<p><a name=\"8\">Intention : La b\u00e9atification de notre V\u00e9n\u00e9rable P\u00e8re.<\/a><\/p>\n<p><a name=\"8\"><strong>\u0084<\/strong><strong> Constitutions 6 :<\/strong><\/a><\/p>\n<p><a name=\"8\">D\u00e9j\u00e0 consacr\u00e9 par le Bapt\u00eame, le Fr\u00e8re, s\u00e9duit par la Personne du Christ, s&#8217;engage \u00e0 l&#8217;imiter de plus pr\u00e8s dans sa forme de vie terrestre chaste, pauvre, ob\u00e9issante, et \u00e0 s&#8217;associer plus intimement \u00e0 son oeuvre de salut.<\/a><\/p>\n<p><a name=\"8\"><strong>\u0084<\/strong><strong> Aux pr\u00eatres de Saint-M\u00e9en, sermon &#8216;La perfection&#8217;, 1839 :<\/strong><\/p>\n<p>Pour \u00eatre vraiment saint, il ne faut rien de moins que prendre le Saint des saints pour mod\u00e8le et lui devenir semblable, ressemblance qui commence sur la terre o\u00f9 elle est toujours imparfaite, mais qui s\u2019ach\u00e8ve et se consomme dans le ciel.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1966, F. Vincent B\u00e9dard.- 1969, F. Emmanuel Bwete (John Vianney).- 1982, F. Isidore Guitot (Fernand-Louis).- 2003, F. Lionel Trudel (Antonin-Jean).- 2011, F. Raymond Berube (Raymond-Albert).- 2017, F. Paul Caron (Edouard-Jean).- 2019, F. Guy Lambert (Laurent-Guy)<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"8\"><\/a><a name=\"8\"><\/a><a name=\"8\"><\/a><a name=\"8\"><\/a><a name=\"_Toc518119391\"><\/a><a name=\"_Toc518187331\"><\/a><a name=\"_Toc46533761\"><\/a><\/p>\n<p><strong><a name=\"9\">9&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; MERCREDI<\/a><\/strong><a name=\"9\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"9\"><br \/>\n<\/a><\/p>\n<ol start=\"375\"><a name=\"9\"><br \/>\n<\/a><\/p>\n<li><a name=\"9\"><\/a><a name=\"_Toc518119393\"><\/a><a name=\"_Toc518119394\"><\/a> \u00c9phrem, diacre, D., \u2020 375.<\/li>\n<li>Prime, \u2020 286 et F\u00e9licien, \u2020 240, Mm.<\/li>\n<\/ol>\n<p>1973.- B\u00e9n\u00e9diction de la Maison g\u00e9n\u00e9ralice de Rome.<\/p>\n<p>Intention : La communaut\u00e9 de la Maison g\u00e9n\u00e9ralice (Rome).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 7 :<\/strong><\/p>\n<p>Le Fr\u00e8re exprime son engagement par la profession publique des trois voeux de religion, cons\u00e9cration particuli\u00e8re qui s&#8217;enracine dans celle du Bapt\u00eame d\u00e8s lors manifest\u00e9e avec plus de pl\u00e9nitude. Dans l&#8217;instant&nbsp; m\u00eame, il offre \u00e0 Dieu sa vie tout enti\u00e8re.<\/p>\n<p><strong>\u0084<\/strong> <strong>Instructions aux fr\u00e8res de la Guadeloupe, le 26 novembre 1837<\/strong><strong> :<\/strong><\/p>\n<p>Les Fr\u00e8res auront la plus tendre d\u00e9votion envers la tr\u00e8s sainte Vierge : ils auront recours \u00e0 elle tr\u00e8s souvent, comme \u00e0 leur M\u00e8re, et ils s\u2019efforceront, en imitant ses vertus, de m\u00e9riter qu\u2019elle attire les b\u00e9n\u00e9dictions de Dieu sur leurs travaux.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1963, F. Germain-Antoine Poupon.- 2005, F. Maurice Plourde (Matthieu).- 2007, F. G\u00e9rard Brodeur (Fernand-G\u00e9rard).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) : <a name=\"_Toc518119397\"><\/a><a name=\"_Toc518187332\"><\/a><a name=\"_Toc46533762\"><\/a><\/p>\n<p><strong><a name=\"10\">10&nbsp;&nbsp;&nbsp;&nbsp; JEUDI&nbsp;<\/a><\/strong><a name=\"10\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie<\/a><\/p>\n<p><a name=\"10\">1926.- D\u00e9part de La Prairie (Canada) des quatre premiers Fr\u00e8res pour l\u2019Ouganda.<\/a><\/p>\n<p><a name=\"10\">Intention : La communaut\u00e9 de Mount Saint Teresa, Kisubi (Ouganda).<\/a><\/p>\n<p><a name=\"10\">(Au br\u00e9viaire, 1\u00e8res v\u00eapres du Sacr\u00e9-C\u0153ur)<\/a><\/p>\n<p><a name=\"10\"><strong>\u0084<\/strong><strong> Constitutions 8 :<\/strong><\/p>\n<p>La profession est aussi un contrat par lequel le Fr\u00e8re s&#8217;engage en toute libert\u00e9 \u00e0 observer la R\u00e8gle de Vie de la Congr\u00e9gation&nbsp;; celle-ci, de son c\u00f4t\u00e9, lui assure les conditions et les moyens tant spirituels que mat\u00e9riels qui lui permettront de r\u00e9aliser sa vie et sa mission de Fr\u00e8re.<\/p>\n<p><strong>\u0084<\/strong><strong> Aux pr\u00eatres de Saint-M\u00e9en, ouverture de la retraite de 1826 :<\/strong><\/p>\n<p>La Tr\u00e8s Sainte Vierge, notre patronne et notre protectrice sp\u00e9ciale, est en ce moment en pri\u00e8re avec nous, et, sans doute, si nous ne mettons aucun obstacle \u00e0 l\u2019efficacit\u00e9 de ses pri\u00e8res, nous allons obtenir par elle les gr\u00e2ces les plus excellentes et les plus pr\u00e9cieuses.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1996, F. Simon Bergeron (Florian-Robert).- 2000, F. Victor Dubourg (Louis-Henri).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"10\"><\/a><a name=\"10\"><\/a><a name=\"10\"><\/a><a name=\"10\"><\/a><a name=\"_Toc518119398\"><\/a><a name=\"_Toc518187333\"><\/a><a name=\"_Toc46533763\"><\/a><strong><a name=\"11\">11&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"11\"><strong>VENDREDI &nbsp;&nbsp;LE SACRE-C\u0152UR (1)<\/strong><\/a><\/p>\n<p><a name=\"11\"><br \/>\n<\/a><\/p>\n<ol><a name=\"11\"><br \/>\n<\/a><\/p>\n<li><a name=\"11\"><\/a><a name=\"_Toc518119399\"><\/a> Barnab\u00e9, ap\u00f4tre, 1er s. (3).<\/li>\n<li><a name=\"_Toc518119400\"><\/a> Parisio, Camaldule, \u2020 1367.<\/li>\n<\/ol>\n<p>1924.- D\u00e9cret apostolique confirmant la r\u00e9putation de saintet\u00e9 de notre V\u00e9n\u00e9rable P\u00e8re.<\/p>\n<p>Journ\u00e9e mondiale pour la sanctification des pr\u00eatres<\/p>\n<p>Intention : &#8211; Les pr\u00eatres de nos paroisses et nos aum\u00f4niers<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 9 :<\/strong><\/p>\n<p>Les voeux sont \u00e9mis pour un temps d&#8217;abord et ensuite \u00e0 perp\u00e9tuit\u00e9. Ils sont re\u00e7us, au nom de l&#8217;\u00c9glise, par le Sup\u00e9rieur G\u00e9n\u00e9ral ou par son d\u00e9l\u00e9gu\u00e9. Le cas \u00e9ch\u00e9ant, il sera fait mention de cette d\u00e9l\u00e9gation dans le registre officiel de profession.<\/p>\n<p><strong>\u0084<\/strong><strong> Aux fr\u00e8res, Avis pour la retraite :<\/strong><\/p>\n<p>Daigne le Seigneur faire de vous des hommes selon son Coeur, d\u00e9vou\u00e9s \u00e0 son \u00c9glise, d\u00e9tach\u00e9s d\u2019eux-m\u00eames, pauvres en esprit, humbles, z\u00e9l\u00e9s, pr\u00eats \u00e0 tout entreprendre et \u00e0 tout souffrir.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1974, F. Charles Bocherel (Clair-Joseph).- 1975, F. Honorio Saiz (Narciso).- 2006, F. Louis-Joseph Legendre (Lucien-Jean).- 2011, F. Joseph Mosset (Pierre-Louis).- 2014, F. Raymond \u00c9meraud (Philibert-Marie).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119401\"><\/a><a name=\"_Toc518187334\"><\/a><a name=\"_Toc46533764\"><\/a><strong><a name=\"12\">12&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"12\"><strong>SAMEDI<\/strong> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Le C\u0153ur Immacul\u00e9 de Marie (3)<\/a><\/p>\n<p><a name=\"12\"><em>La Chapelle de la Maison-M\u00e8re de Plo\u00ebrmel est d\u00e9di\u00e9e au C\u0153ur de Marie.<\/em><\/a><\/p>\n<p><a name=\"12\"><\/a><\/p>\n<p><a name=\"12\"><\/a><\/p>\n<p><a name=\"12\"><\/p>\n<ol start=\"1247\">\n<li>Guy, franciscain italien, \u2020 1247.<\/li>\n<\/ol>\n<p>Intention : &#8211; La communaut\u00e9 de la Maison-M\u00e8re (Plo\u00ebrmel).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 11 a :<\/strong><\/p>\n<p>Pour appartenir plus facilement \u00e0 Dieu d&#8217;un coeur sans partage, et suivre de plus pr\u00e8s le Christ, les Fr\u00e8res choisissent la chastet\u00e9 parfaite dans le c\u00e9libat pour le Royaume des Cieux.<\/p>\n<p><strong>\u0084<\/strong><strong> \u00c0 Melle Amable Chenu, le 27 janvier 1821<\/strong><\/p>\n<p>Il faut que votre c\u0153ur devienne semblable au C\u0153ur de Marie, qu\u2019il soit anim\u00e9 du m\u00eame esprit de charit\u00e9, d\u2019humilit\u00e9, de z\u00e8le, de douceur, de puret\u00e9, de d\u00e9tachement des choses sensibles.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1963, F. Jean-Yves G\u00e9linas.- 1965, F. Louis-Pierre Lampron.- 1973, F. Henri Lozach (L\u00e9onide-Marie).- 1997, F. Alain Gentric (Gon\u00e9ry).- 2006, F. Yvan Lampron (Achille-Ren\u00e9).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"12\"><\/a><a name=\"12\"><\/a><a name=\"12\"><\/a><a name=\"12\"><\/a><a name=\"_Toc518119404\"><\/a><a name=\"_Toc518187335\"><\/a><a name=\"_Toc46533765\"><\/a><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><a name=\"13\">13&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"13\"><strong>DIMANCHE&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 11\u00e8me&nbsp; du temps ordinaire<\/strong><\/a><\/p>\n<p><a name=\"13\"><br \/>\n<\/a><\/p>\n<ol><a name=\"13\"><br \/>\n<\/a><\/p>\n<li><a name=\"13\"><\/a><a name=\"_Toc518119405\"><\/a> Antoine de Padoue, franciscain portugais, D., \u2020 1231 (3).<\/li>\n<\/ol>\n<p>Au br\u00e9viaire, troisi\u00e8me&nbsp; semaine.<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 11 b :<\/strong><\/p>\n<p>Le c\u00e9libat consacr\u00e9 est une anticipation de la vie de la R\u00e9surrection. Il \u00e9voque d&#8217;une mani\u00e8re sp\u00e9ciale l&#8217;union de l&#8217;\u00c9glise avec son unique \u00c9poux. Il \u00ab&nbsp;lib\u00e8re singuli\u00e8rement le coeur de l&#8217;homme pour qu&#8217;il br\u00fble de l&#8217;amour de Dieu et de tous les hommes&nbsp;\u00bb (PC 12, 1).<\/p>\n<p><strong>\u0084<\/strong><strong> \u00c0 Brut\u00e9 de R\u00e9mur, le 4 juillet 1807 :<\/strong><\/p>\n<p>Il ne faut pas pr\u00e9cipiter l\u2019avenir sur le pr\u00e9sent, ou nous serons \u00e9cras\u00e9s. Ne pr\u00e9voyons pas trop&nbsp;; c\u2019est le Saint-Esprit qui nous le conseille.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1970, F. \u00c9mile Goulet (Th\u00e9ophane).- 1979, F. Siro de Ambrosis (Augustin-Cyr).- 2002, F. Arsenio Bustamante Escalada (Estanislao).- 2005, F. Maurice Blais (Victor-Maurice).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119406\"><\/a><a name=\"_Toc518187336\"><\/a><a name=\"_Toc46533766\"><\/a><\/p>\n<p><strong><a name=\"14\">14&nbsp;&nbsp;&nbsp;&nbsp; LUNDI&nbsp;<\/a><\/strong><a name=\"14\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie<\/a><\/p>\n<p><a name=\"14\">Intention : La communaut\u00e9 de Kabojja (Ouganda).<\/a><\/p>\n<p><a name=\"14\"><strong>\u0084<\/strong><strong> Constitutions 12 :<\/strong><\/a><\/p>\n<p><a name=\"14\">Par le voeu de chastet\u00e9, les Fr\u00e8res s&#8217;engagent \u00e0 vivre la vertu de chastet\u00e9 parfaite dans le c\u00e9libat.<\/a><\/p>\n<p><a name=\"14\"><strong>\u0084<\/strong><strong> Au F. Andr\u00e9 Labousse, le 24 mai 1824 :<\/strong><\/p>\n<p>Ne contristez point l\u2019Esprit Saint par ces infid\u00e9lit\u00e9s continuelles qui l\u2019emp\u00eachent de vous remplir de l\u2019abondance de ses dons et de ses gr\u00e2ces.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1983, F. Vincent Jolivet (Jean Damasc\u00e8ne).- 2016, F. Gaston Manceau (Yves-Alexandre).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"14\"><\/a><a name=\"14\"><\/a><a name=\"14\"><\/a><a name=\"14\"><\/a><a name=\"_Toc518119408\"><\/a><a name=\"_Toc518187337\"><\/a><a name=\"_Toc46533767\"><\/a><\/p>\n<p><strong><a name=\"15\">15&nbsp;&nbsp;&nbsp;&nbsp; MARDI &nbsp;<\/a><\/strong><a name=\"15\">&nbsp;&nbsp;&nbsp; de la f\u00e9rie<\/a><\/p>\n<p><a name=\"15\"><strong>Intention<\/strong> : Pour que naisse un nouvel \u00e9lan missionnaire dans notre Congr\u00e9gation.<\/a><\/p>\n<p><a name=\"15\"><strong>\u0084<\/strong><strong> Constitutions 13 :<\/strong><\/a><\/p>\n<p><a name=\"15\">La vie de chastet\u00e9 demande des renoncements qui s&#8217;imposent \u00e0 tout chr\u00e9tien et d&#8217;autres qu&#8217;un religieux prudent d\u00e9couvre \u00ab comme par un instinct spirituel \u00bb (PC&nbsp;12,2).<\/a><\/p>\n<p><a name=\"15\"><strong>\u0084<\/strong><strong> Au F. M\u00e9loir-Marie Lef\u00e8vre, 1834 :<\/strong><\/p>\n<p>Vouloir tout ce que Dieu veut et le vouloir pour toujours, pour tout, sans r\u00e9serve, voil\u00e0 ce royaume de Dieu dont nous lui demandons l\u2019av\u00e8nement chaque fois que nous r\u00e9citons le Pater.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1961, F. Louis-\u00c9douard Dubois.- 1969, F. Ad\u00e9lard Dupr\u00e9 (\u00c9piphane).<\/p>\n<p><\/a><a name=\"15\"><\/a><a name=\"15\"><\/a><a name=\"15\"><\/a><a name=\"15\">\u00c9v\u00e9nement(s) et anniversaire(s) : <\/a><a name=\"_Toc518119410\"><\/a><a name=\"_Toc518187338\"><\/a><a name=\"_Toc46533768\"><\/a><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><a name=\"16\">16&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"16\"><strong>MERCREDI &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong>de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"16\"><br \/>\n<\/a><\/p>\n<ol start=\"1640\"><a name=\"16\"><br \/>\n<\/a><\/p>\n<li><a name=\"16\"><\/a><a name=\"_Toc518119412\"><\/a> Jean-Fran\u00e7ois R\u00e9gis, j\u00e9suite fran\u00e7ais, \u2020 1640.<\/li>\n<\/ol>\n<p>Intention : Nos Fr\u00e8res malades et infirmes.<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 14 a :<\/strong><\/p>\n<p>La chastet\u00e9, fruit de l&#8217;intimit\u00e9 avec Dieu est une gr\u00e2ce insigne que les Fr\u00e8res ont \u00e0 coeur de solliciter dans la pri\u00e8re et la r\u00e9ception des Sacrements de la R\u00e9conciliation et de l&#8217;Eucharistie.<\/p>\n<p><strong>\u0084<\/strong><strong> \u00c0 l&#8217;abb\u00e9 \u00c9vain, le 29 mai 1842 :<\/strong><\/p>\n<p>Recommandez souvent aux Fr\u00e8res de se tenir en garde contre les pr\u00e9ventions qui s\u2019emparent quelquefois de l\u2019esprit sans qu\u2019on s\u2019en aper\u00e7oive et contre les jalouses d\u00e9fiances qui troublent la paix, aigrissent l\u2019esprit et rompent l\u2019union des coeurs, union si n\u00e9cessaire, union si pr\u00e9cieuse<\/p>\n<p>D\u00c9FUNT<\/p>\n<p>1995, F. Bernard Levesque (Richard).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119415\"><\/a><a name=\"_Toc518187339\"><\/a><a name=\"_Toc46533769\"><\/a><\/p>\n<p><strong><a name=\"17\">17&nbsp;&nbsp;&nbsp;&nbsp; JEUDI&nbsp;&nbsp;<\/a><\/strong><a name=\"17\"> &nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"17\"><br \/>\n<\/a><\/p>\n<ol><a name=\"17\"><br \/>\n<\/a><\/p>\n<li><a name=\"17\"><\/a><a name=\"_Toc518119418\"><\/a> Herv\u00e9, ermite en Bretagne, \u2020 6e s.<\/li>\n<\/ol>\n<p><strong>\u0084<\/strong><strong> Directoire 105 a :<\/strong><\/p>\n<p>Dans la fid\u00e9lit\u00e9 \u00e0 leur vocation propre et \u00e0 l&#8217;enseignement de leurs Fondateurs, les Fr\u00e8res apportent un soin sp\u00e9cial \u00e0 r\u00e9pondre aux directives pastorales du Pape et des \u00c9v\u00eaques, premiers responsables de l&#8217;apostolat.<\/p>\n<p><strong>\u0084<\/strong><strong> \u00c0 des congr\u00e9ganistes, sermon &#8216;Sur la m\u00e9disance&#8217; :<\/strong><\/p>\n<p>Ne vous suffit-il pas de savoir que rien n\u2019est plus oppos\u00e9 \u00e0 l\u2019esprit du christianisme que ces censures pleines de malignit\u00e9, pour que vous ne vous en permettiez jamais aucune&nbsp;?<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1981, F. Adri\u00e1n Santos (Arturo Jos\u00e9).- 1997, F. Jean P\u00e9nargu\u00e9ar (Paul-Henri).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119419\"><\/a><a name=\"_Toc518187340\"><\/a><a name=\"_Toc46533770\"><\/a><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><a name=\"18\">18&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"18\"><strong>VENDREDI&nbsp; <\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"18\"><br \/>\n<\/a><\/p>\n<ol start=\"304\"><a name=\"18\"><br \/>\n<\/a><\/p>\n<li><a name=\"18\"><\/a><a name=\"_Toc518119420\"><\/a> Marc et Marcellin, Mm., \u2020 304.<\/li>\n<\/ol>\n<p><em>Neuvaine de pri\u00e8re pour la b\u00e9atification de Jean-Marie de la Mennais&nbsp;; pri\u00e8re, page 15.<\/em><\/p>\n<p>Intention : La communaut\u00e9 de l\u2019infirmerie, La Prairie (Canada).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 15 a :<\/strong><\/p>\n<p>Afin de participer plus intimement \u00e0 la pauvret\u00e9 du Christ qui a choisi de vivre pauvre parmi les pauvres, et de d\u00e9tacher leur coeur de ce qu&#8217;ils poss\u00e8dent et de ce qu&#8217;ils sont, les Fr\u00e8res font le voeu de pauvret\u00e9.<\/p>\n<p><strong>\u0084<\/strong><strong> Au F. Andr\u00e9 Labousse, le 24 mai 1824 :<\/strong><\/p>\n<p>Quand donc serez-vous tout \u00e0 fait \u00e0 Dieu ? Pourquoi refusez-vous de lui offrir les l\u00e9gers sacrifices qu\u2019il vous demande ?<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1976,&nbsp; &nbsp;F.&nbsp; &nbsp;Mathias&nbsp; Gerbeau&nbsp; (L\u00e9onidas-Joseph).-&nbsp; 1988, F. Auguste Bergeron (Archange-Marie).- 1998, F. Pierre-Marie Le Cheviller (Gu\u00e9rin-Marie).- 2008, F. Jean-Paul Larocque (Gustave-Joseph).- 2012, F. Pierre Tousignant<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119421\"><\/a><a name=\"_Toc518187341\"><\/a><a name=\"_Toc46533771\"><\/a><\/p>\n<p><strong><a name=\"19\">19&nbsp;&nbsp;&nbsp;&nbsp; SAMEDI&nbsp;&nbsp;<\/a><\/strong><a name=\"19\">&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"19\"><br \/>\n<\/a><\/p>\n<ol start=\"1027\"><a name=\"19\"><br \/>\n<\/a><\/p>\n<li><a name=\"19\"><\/a><a name=\"_Toc518119424\"><\/a><a name=\"_Toc518119422\"><\/a> Romuald, abb\u00e9, fondateur des Camaldules, \u2020 1027.<\/li>\n<li>Gervais et Protais, Mm. \u00e0 Milan, \u2020 225.<\/li>\n<\/ol>\n<p><em>Deuxi\u00e8me jour de la neuvaine (page 15).<\/em><\/p>\n<p>Intention : La communaut\u00e9 de Saint-Romuald Atkinson (Canada).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 15 b :<\/strong><\/p>\n<p>Les Fr\u00e8res peuvent ainsi, dans l&#8217;esprit des B\u00e9atitudes v\u00e9cues par la communaut\u00e9 des Ap\u00f4tres, devenir plus disponibles pour Dieu et pour les autres, surtout les plus d\u00e9favoris\u00e9s.<\/p>\n<p><strong>\u0084<\/strong><strong> Au F. Louis-Joseph Bodo, le 10 juin 1843 :<\/strong><\/p>\n<p>Toutes vos actions doivent \u00eatre sanctifi\u00e9es par l\u2019ob\u00e9issance et elles cesseraient d\u2019\u00eatre agr\u00e9ables \u00e0 Dieu si vous les faisiez en dehors des r\u00e8gles qui vous sont prescrites.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1981, F. Laurent Rozon (Tite).- 1995, F. Franck D\u2019M\u00e9za (Philippe-Marie).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119425\"><\/a><a name=\"_Toc518187342\"><\/a><a name=\"_Toc46533772\"><\/a><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><a name=\"20\">20&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"20\"><strong>DIMANCHE <\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <strong>12\u00e8me&nbsp; du temps ordinaire<\/strong><\/a><\/p>\n<p><a name=\"20\"><em>Troisi\u00e8me jour de la neuvaine (page 15).<\/em><\/a><\/p>\n<p><a name=\"20\">Intentions : Le succ\u00e8s spirituel de nos retraites annuelles.<\/a><\/p>\n<p><a name=\"20\">Au br\u00e9viaire, quatri\u00e8me&nbsp; semaine.<\/a><\/p>\n<p><a name=\"20\"><strong>\u0084<\/strong> <strong>Constitutions 16 :<\/strong><\/p>\n<p>Par le voeu de pauvret\u00e9, les Fr\u00e8res renoncent \u00e0 la disposition et \u00e0 l&#8217;usage ind\u00e9pendants et libres de tout bien temporel estimable \u00e0 prix d&#8217;argent.<\/p>\n<p><strong>\u0084<\/strong> <strong>\u00c0 des religieuses, discours pour la maison du Refuge de Saint-Brieuc, le 10 f\u00e9vrier 1822 :<\/strong><\/p>\n<p>Dieu veut que, dans ses ouvrages, sa main paraisse seule et qu\u2019ils portent le caract\u00e8re de sa haute sagesse. Il n\u2019avance que par degr\u00e9s et ne consomme ses desseins que lorsque toute esp\u00e9rance humaine de les voir s\u2019accomplir est enti\u00e8rement \u00e9teinte.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1967,&nbsp; F.&nbsp; Roland-Marie&nbsp; Ricordel.-&nbsp; 1968,&nbsp; F. Donatien Caillon (Euchariste-Joseph).- 1976, F. Joseph Tonnerre (Tudy-Joseph).- 1981, F. Yves Cabel (Yves-Joseph).- 1984, F. Pierre Tanguy (Benjamin).- 2003, F. Godfrey Lule.- 2014, F. Louis K\u00e9rivel (Louis-Armel).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"20\"><\/a><a name=\"20\"><\/a><a name=\"20\"><\/a><a name=\"20\"><\/a><a name=\"_Toc518119427\"><\/a><a name=\"_Toc518187343\"><\/a><a name=\"_Toc46533773\"><\/a><strong><a name=\"21\">21&nbsp;&nbsp;&nbsp;&nbsp; LUNDI&nbsp;<\/a><\/strong><a name=\"21\"> &nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"21\"><br \/>\n<\/a><\/p>\n<ol><a name=\"21\"><br \/>\n<\/a><\/p>\n<li><a name=\"21\"><\/a><a name=\"_Toc518119428\"><\/a> Louis de Gonzague, j\u00e9suite, patron de nos scolasticats, \u2020 1591 (3).<\/li>\n<\/ol>\n<p><em>Quatri\u00e8me jour de la neuvaine (page 15).<\/em><\/p>\n<p>Intentions : &#8211; Les Fr\u00e8res de la Province Saint-Louis-de-Gonzague (Ha\u00efti)<\/p>\n<p>&#8211; Les Fr\u00e8res scolastiques.<\/p>\n<p>&#8211; La communaut\u00e9 du Postulat et du Noviciat, P\u00e9tion-Ville (Ha\u00efti).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 17 a :<\/strong><\/p>\n<p>Les prof\u00e8s de voeux perp\u00e9tuels qui le d\u00e9sirent peuvent renoncer, en tout ou en partie, \u00e0 leurs biens temporels. Cette renonciation ne peut se faire avant cinq ans de voeux perp\u00e9tuels et sans l&#8217;accord pr\u00e9alable du Sup\u00e9rieur G\u00e9n\u00e9ral du consentement de son Conseil. Dans leur d\u00e9cision, les Fr\u00e8res tiennent compte des convenances familiales, des besoins des indigents, de ceux de leur Institut et de l&#8217;\u00c9glise.<\/p>\n<p><strong>\u0084<\/strong><strong> Au F. Ferdinand Tourtier, le 1er f\u00e9vrier 1842 :<\/strong><\/p>\n<p>Oui, mon cher enfant, vous avez bien raison de dire que votre bonheur est l&#8217;objet de tous mes travaux et de tous mes d\u00e9sirs, mais, surtout, ne l&#8217;oubliez point, votre bonheur dans l&#8217;\u00e9ternit\u00e9 !<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1966, F. Simplicius Nevou.- 1971, F. Fr\u00e9d\u00e9ric Perreault (Fr\u00e9d\u00e9ric-Marie).- 1976, F. Charles Berthier (Charles-Yves).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<a name=\"_Toc518119430\"><\/a><a name=\"_Toc518187344\"><\/a><a name=\"_Toc46533774\"><\/a><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><a name=\"22\">22&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"22\"><strong>MARDI <\/strong>&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"22\"><br \/>\n<\/a><\/p>\n<ol start=\"431\"><a name=\"22\"><br \/>\n<\/a><\/p>\n<li><a name=\"22\"><\/a><a name=\"_Toc518119432\"><\/a> Paulin de Nolle, \u00c9v., \u2020 431.<\/li>\n<li>Alban, premier martyr d\u2019Angleterre, \u2020 287.<\/li>\n<li><a name=\"_Toc518119433\"><\/a> John Fisher et Thomas More, martyrs en Angleterre, \u2020 1535.<\/li>\n<\/ol>\n<p><em>Cinqui\u00e8me jour de la neuvaine (page 15).<\/em><\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 17 b :<\/strong><\/p>\n<p>Le prof\u00e8s qui renonce \u00e0 tous ses biens, pr\u00e9sents et \u00e0 venir, perd la capacit\u00e9 d&#8217;acqu\u00e9rir et de poss\u00e9der. D\u00e8s lors, tout acte contraire \u00e0 cette disposition est nul. Tout ce qui lui \u00e9choit revient \u00e0 la Congr\u00e9gation.<\/p>\n<p><strong>\u0084<\/strong> <strong>Aux fr\u00e8res, retraite de 1835 :<\/strong><\/p>\n<p>Je d\u00e9sire vivement que nous ne voyions plus de ces hommes qui s\u2019efforcent de concilier ce qui est inconciliable&nbsp;: les principes de l\u2019\u00c9vangile et les id\u00e9es du monde.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1968, F. Alphonse Delisle (Joseph-Hermann).- 1987, F. Albert Gentric (Gr\u00e9goire-Joseph).<\/p>\n<p><a name=\"_Toc518119434\"><\/a><a name=\"_Toc518187345\"><\/a><a name=\"_Toc46533775\"><\/a><strong><a name=\"23\">23&nbsp;&nbsp;&nbsp;&nbsp; MERCREDI<\/a><\/strong><a name=\"23\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie<\/a><\/p>\n<p><a name=\"23\"><em>Sixi\u00e8me jour de la neuvaine (page 15).<\/em><\/a><\/p>\n<p><a name=\"23\">(Au br\u00e9viaire, 1\u00e8res v\u00eapres de la St Jean-Baptiste).<\/a><\/p>\n<p><a name=\"23\"><strong>\u0084<\/strong><strong> Constitutions 18 :<\/strong><\/a><\/p>\n<p><a name=\"23\">Les Fr\u00e8res qui ne font pas la renonciation \u00e0 tous leurs biens temporels conservent la nue propri\u00e9t\u00e9 de leur patrimoine et la capacit\u00e9 d&#8217;acqu\u00e9rir d&#8217;autres biens par h\u00e9ritage ou donation&nbsp;; mais ils doivent c\u00e9der l&#8217;administration, l&#8217;usufruit et l&#8217;usage de leurs biens \u00e0 qui ils veulent, m\u00eame \u00e0 leur Institut s&#8217;ils le pr\u00e9f\u00e8rent. Cette cession se fait par \u00e9crit, avant la premi\u00e8re profession s&#8217;ils ont d\u00e9j\u00e0 des biens, ou lorsqu&#8217;ils en acqui\u00e8rent.<\/p>\n<p><strong>\u0084<\/strong><strong> Sermon aux pr\u00eatres de Saint-M\u00e9en :<\/strong><\/p>\n<p>Nous devons aimer l\u2019\u00c9glise comme nous aimons J\u00e9sus-Christ dont elle est l\u2019\u00e9pouse et qui ne fait avec elle qu\u2019un m\u00eame corps et une m\u00eame chair, c\u2019est-\u00e0-dire de tout notre c\u0153ur, de toute notre volont\u00e9 et de toutes nos forces.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1976, F. Marcel De Serre (Miza\u00ebl).- 1980, F. Louis-Charles Mayrand (Ir\u00e9n\u00e9e-Joseph).- 1990, F.&nbsp;Ulysse Saint-Martin (Jules-Joseph).- 1994, F. Alexandre Desrochers (Marc-Alexandre).- 2003, F. Joseph Milot (Simon-Marie).- 2004, F. Mathieu Kerou\u00e9dan (Corentin-Pierre).- 2006, F.&nbsp;Lionel Morneau (Omer-Marie). 2019, F. Juan Guimard (Barth\u00e9l\u00e9my-Joseph)<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"23\"><\/a><a name=\"23\"><\/a><a name=\"23\"><\/a><a name=\"23\"><\/a><a name=\"_Toc518119436\"><\/a><a name=\"_Toc518187346\"><\/a><a name=\"_Toc46533776\"><\/a><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><a name=\"24\">24&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"24\"><strong>JEUDI&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><\/a><strong><a name=\"_Toc518119437\"><\/a>NATIVIT\u00c9 DE S. JEAN-BAPTISTE<\/strong> (1), Patron sp\u00e9cial des canadiens fran\u00e7ais<\/p>\n<p><em>Septi\u00e8me jour de la neuvaine (page 15).<\/em><\/p>\n<p>Intention : Les Fr\u00e8res de la Province St-Jean-Baptiste (France-Angleterre).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 19 :<\/strong><\/p>\n<p>Au plus tard avant leur profession perp\u00e9tuelle ou d\u00e8s qu&#8217;ils acqui\u00e8rent des biens, les Fr\u00e8res disposent librement de leur avoir par un testament valide au for civil.<\/p>\n<p><strong>\u0084<\/strong><strong> \u00c0 Brut\u00e9 de R\u00e9mur, le 22 juin 1809:<\/strong><\/p>\n<p>F\u00eate de saint Jean-Baptiste, f\u00eate de fr\u00e8re Jean. Demandez donc au bon Dieu qu&#8217;il cr\u00e9e en moi un c\u0153ur pur, un c\u0153ur qui l&#8217;aime ! Demandez-lui qu&#8217;il me fasse la gr\u00e2ce d&#8217;\u00eatre tout \u00e0 lui, \u00e0 lui seul, et pour toujours.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>2004, F. Arthur Sylvestre (Marcel-\u00c9mile).- 2012, F. Corentin Coton\u00e9a (Yves-Laurent).- 2018, F Philippe Ozawa.<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119438\"><\/a><a name=\"_Toc518187347\"><\/a><a name=\"_Toc46533777\"><\/a><strong><a name=\"25\">25&nbsp;&nbsp;&nbsp;&nbsp; VENDREDI &nbsp;<\/a><\/strong><a name=\"25\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"25\"><br \/>\n<\/a><\/p>\n<ol start=\"1142\"><a name=\"25\"><br \/>\n<\/a><\/p>\n<li><a name=\"25\"><\/a><a name=\"_Toc518119439\"><\/a> Guillaume, abb\u00e9, \u2020 1142.<\/li>\n<\/ol>\n<p><em>Huiti\u00e8me jour de la neuvaine (page 15).<\/em><\/p>\n<p>Intention : La communaut\u00e9 Gabriel Deshayes, Abidjan (C\u00f4te d\u2019Ivoire).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 20 :<\/strong><\/p>\n<p>Pour modifier les dispositions administratives ou testamentaires, il faut l&#8217;autorisation du Sup\u00e9rieur G\u00e9n\u00e9ral&nbsp;; en cas d&#8217;urgence, celle du Fr\u00e8re Provincial ou &nbsp;Visiteur suffit.<\/p>\n<p><strong>\u0084<\/strong><strong> Circulaire pour la retraite, le 13 juin 1824 :<\/strong><\/p>\n<p>En voyant approcher les jours de notre retraite annuelle, vous devez vous r\u00e9jouir dans le Seigneur et vous pr\u00e9parer \u00e0 profiter des gr\u00e2ces toutes sp\u00e9ciales qui vous seront offertes dans ce saint temps.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1980, F. Pierre Verdon (\u00c9lie).- 2007, F. Pius Kihuru.<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119441\"><\/a><a name=\"_Toc518187348\"><\/a><a name=\"_Toc46533778\"><\/a><strong><a name=\"26\">26&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"26\"><strong>SAMEDI &nbsp;&nbsp; <\/strong>&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"26\"><\/a><\/p>\n<p><a name=\"26\"><\/a><\/p>\n<p><a name=\"26\"><\/a><\/p>\n<p><a name=\"26\"><\/p>\n<ol start=\"1975\">\n<li>Jos\u00e9 Mar\u00eda Escriv\u00e1 de Balaguer, \u2020 1975.<\/li>\n<\/ol>\n<p><em>Dernier jour de la neuvaine (page 15).<\/em><\/p>\n<p>Intention : La b\u00e9atification de notre V\u00e9n\u00e9rable P\u00e8re.<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 21 :<\/strong><\/p>\n<p>Les prof\u00e8s peuvent accomplir les actes de propri\u00e9t\u00e9 pr\u00e9vus par les lois, pourvu qu&#8217;ils le fassent avec l&#8217;autorisation du Fr\u00e8re Provincial ou Visiteur.<\/p>\n<p><strong>\u0084<\/strong><strong> Aux pr\u00eatres de Saint-M\u00e9en, sermon Abandon \u00e0 la Providence&#8217; :<\/strong><\/p>\n<p>La r\u00e8gle de mes pens\u00e9es et de ma conduite est de vouloir ce que Dieu veut, comme il le veut, quand il le veut.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1972, F. Jean-Pierre Gru (Herv\u00e9).- 1976, F. Jean-Marie Diascorn (Octavien-Marie).- 1981, F. Am\u00e9d\u00e9e Patenaude (Albertin-Joseph).- 1993, F. Fran\u00e7ois Proulx (Victoric-Marie).- 2001, F. Herv\u00e9 Lucas (Norbert-Joseph).- 2003, F. Henri \u00c9zanno (Stanislas-Pierre).- 2013, F. Paul Charest (Beno\u00eet-\u00c9mile).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><\/a><a name=\"26\"><\/a><a name=\"26\"><\/a><a name=\"26\"><\/a><a name=\"26\"><\/a><a name=\"_Toc518119444\"><\/a><a name=\"_Toc518187349\"><\/a><a name=\"_Toc46533779\"><\/a><\/p>\n<p><strong><a name=\"27\">27&nbsp;&nbsp;&nbsp;&nbsp; DIMANCHE &nbsp;<\/a><\/strong><a name=\"27\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <strong>13\u00e8me&nbsp; du temps ordinaire<\/strong><\/a><\/p>\n<p><a name=\"27\"><br \/>\n<\/a><\/p>\n<ol start=\"444\"><a name=\"27\"><br \/>\n<\/a><\/p>\n<li><a name=\"27\"><\/a><a name=\"_Toc518119445\"><\/a> Cyrille d\u2019Alexandrie, \u00c9v., D., \u2020 444.<\/li>\n<\/ol>\n<p><a name=\"_Toc518119446\"><\/a>N.-D. du Perp\u00e9tuel Secours, patronne d\u2019Ha\u00efti.<\/p>\n<p>Intention : Les Fr\u00e8res de la Province Saint-Louis de Gonzague (Ha\u00efti) et les Fr\u00e8res des \u00c9tats-Unis.<\/p>\n<p>Au br\u00e9viaire, premi\u00e8re&nbsp; semaine.<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 22 :<\/strong><\/p>\n<p>Tout ce qui \u00e9choit aux Fr\u00e8res du fait de leur travail ou qu&#8217;ils re\u00e7oivent \u00e0 titre de dons, de pensions, d&#8217;assurances, ou de quelque autre mani\u00e8re, appartient de droit \u00e0 la Congr\u00e9gation et doit donc lui \u00eatre fid\u00e8lement et promptement remis, selon les normes propres \u00e0 chaque Province ou District.<\/p>\n<p><strong>\u0084<\/strong><strong> Circulaire pour la retraite, le 13 juin 1824 :<\/strong><\/p>\n<p>N\u2019attendez pas le moment o\u00f9 commenceront les pieux exercices de la retraite pour vous y disposer&nbsp;; faites-le aujourd\u2019hui par des pri\u00e8res plus ferventes, par une vigilance plus attentive sur vous-m\u00eame et sur toutes vos d\u00e9marches.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1961, F. Gabriel-Joseph Le Coq.- 1986, F. Alphonse Lambert (Alphonse-Maurice).- 2003, F. G\u00e9rard Bourque (Auguste-Eug\u00e8ne).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) : <a name=\"_Toc518119450\"><\/a><a name=\"_Toc518187350\"><\/a><a name=\"_Toc46533780\"><\/a><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong><a name=\"28\">28&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"_Toc518119451\"><\/a><strong>LUNDI&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong>de la f\u00e9rie<\/p>\n<ol>\n<li>Ir\u00e9n\u00e9e, \u00c9v. de Lyon, M., \u2020 202 (3).<\/li>\n<\/ol>\n<p>(Au br\u00e9viaire, 1\u00e8res v\u00eapres de Saint Pierre et Saint Paul).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 23 :<\/strong><\/p>\n<p>Les Fr\u00e8res ne peuvent disposer d&#8217;argent sans en rendre compte. Pour les d\u00e9penses importantes, ils demandent l&#8217;autorisation du Sup\u00e9rieur local et, le cas \u00e9ch\u00e9ant, sollicitent son avis avant de recourir \u00e0 l&#8217;instance comp\u00e9tente. Ils lui soumettent leurs d\u00e9penses courantes selon les modalit\u00e9s d\u00e9finies \u00e0 l&#8217;\u00e9chelon provincial ou de district.<\/p>\n<p>Une permission ne dispense pas du discernement pr\u00e9alable, ni ne supprime la responsabilit\u00e9 personnelle dans la mani\u00e8re d&#8217;en user.<\/p>\n<p><strong>\u0084<\/strong><strong> \u00c0 M. Querret, le 26 janvier 1825 :<\/strong><\/p>\n<p>Point de regrets, point de pr\u00e9voyance inqui\u00e8te&nbsp;; reposez-vous doucement dans le sein de la Providence, c\u2019est le secret du bonheur.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1966, F. S\u00e9raphin-Joseph Miriel.- 1967, F. Jean Haran.- 1969, F. Joseph Gru (Salvius).- 1976, F. Jules Le M\u00e9tayer (Firmin).- 1984, F. James O\u2019Byrne (Columbkill Mary).- 1991, F. Joseph Robin (Lucidas-Joseph).- 1997, F. Louis Scouarnec (Joachim-Joseph). 2008, F. Luc Maynard (Luc-Henri).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119452\"><\/a><a name=\"_Toc518187351\"><\/a><a name=\"_Toc46533781\"><\/a><\/p>\n<p><strong><a name=\"29\">29&nbsp;&nbsp;&nbsp;&nbsp; <\/a><a name=\"_Toc518119453\"><\/a>MARDI &nbsp;&nbsp;&nbsp;&nbsp; SS. &nbsp;Pierre &nbsp;et &nbsp;Paul, &nbsp;ap\u00f4tres&nbsp; (1).<\/strong><\/p>\n<p>Intentions : &#8211; L\u2019\u00c9glise et le Souverain Pontife.<\/p>\n<p>&#8211; Les Fr\u00e8res du District Saint-Paul (B\u00e9nin, C\u00f4te d\u2019Ivoire, Togo, S\u00e9n\u00e9gal).<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 24 :<\/strong><\/p>\n<p>L&#8217;esprit de pauvret\u00e9 conduit bien au-del\u00e0 de l&#8217;objet du voeu. Il porte les Fr\u00e8res \u00e0 d\u00e9gager leur coeur de l&#8217;emprise des valeurs temporelles&nbsp;: confort et commodit\u00e9s de la vie, postes et fonctions, estime et succ\u00e8s, voire m\u00eame \u00e9panouissement culturel.<\/p>\n<p><strong>\u0084<\/strong><strong> \u00c0 Brut\u00e9 de R\u00e9mur, le 2 f\u00e9vrier 1808 ;<\/strong><\/p>\n<p>Si les ennemis de la sainte \u00c9glise mettent en commun leurs talents, leurs moyens, leur haine, leur audace, pourquoi ne pas opposer de concert nos efforts et ne pas nous exciter mutuellement \u00e0 combattre et \u00e0 vaincre ?<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1997, F. Gratien Deslauriers (Ange-C\u00e9lestin).- 2002, F. Louis-Philippe Olivier (Raoul-\u00c9tienne).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n<p><a name=\"_Toc518119454\"><\/a><a name=\"_Toc518187352\"><\/a><a name=\"_Toc46533782\"><\/a><strong><a name=\"30\">30&nbsp;&nbsp;&nbsp;&nbsp; <\/a><\/strong><a name=\"30\"><strong>MERCREDI <\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de la f\u00e9rie ou<\/a><\/p>\n<p><a name=\"30\"><br \/>\n<\/a><a name=\"30\"><\/a><a name=\"_Toc518119456\"><\/a>Les Saints Premiers Martyrs de l\u2019\u00c9glise de Rome, \u2020 1er s.<\/p>\n<ol>\n<li><a name=\"_Toc518119457\"><\/a> Martial, \u00c9v. de Limoges, \u2020 3\u00e8me s.<\/li>\n<li><a name=\"_Toc518119458\"><\/a> Bertrand, \u00c9v. d\u2019Aquil\u00e9e, M., \u2020 1350.<\/li>\n<\/ol>\n<p>Intention : La communaut\u00e9 de Bunia (R.D.C.)<\/p>\n<p><strong>\u0084<\/strong><strong> Constitutions 25 :<\/strong><\/p>\n<p>Les Fr\u00e8res se soumettent g\u00e9n\u00e9reusement \u00e0 la loi universelle du travail, contribuant ainsi au soutien des communaut\u00e9s et des oeuvres de l&#8217;Institut.<\/p>\n<p><strong>\u0084<\/strong><strong> Pens\u00e9e du P\u00e8re Gabriel Deshayes :<\/strong><\/p>\n<p>Soyez simples, mes chers fr\u00e8res, soyez simples&nbsp;: c\u2019est par la simplicit\u00e9 de votre vie que vous plairez \u00e0 Dieu et que vous acquerrez l\u2019estime et l\u2019affection de tous.<\/p>\n<p>D\u00c9FUNTS<\/p>\n<p>1962, F. Romuald-Louis Le Meur.- 1997, F. Alexandre Chesnel (Louis-Marie de Montfort).-&nbsp;2002, F. Jean Gu\u00e9guen (Edme-Marie).- 2014 F. Paul Qu\u00e9guiner (Michel-Paul).<\/p>\n<p>\u00c9v\u00e9nement(s) et anniversaire(s) :<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MOIS DE JUIN Consacr\u00e9 au Coeur Sacr\u00e9 de J\u00e9sus Apostolat de la Pri\u00e8re, intention d\u2019\u00e9vang\u00e9lisation * * * * * * * * La beaut\u00e9 du mariage&nbsp;: Prions pour les jeunes qui se pr\u00e9parent au mariage avec le soutien d&#8217;une communaut\u00e9 chr\u00e9tienne : qu&#8217;ils grandissent dans l&#8217;amour, avec g\u00e9n\u00e9rosit\u00e9, fid\u00e9lit\u00e9 et patience. 1 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp; MARDI [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-28415","post","type-post","status-publish","format-standard","hentry","category-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juin 2021 - LaMennais.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lamennais.org\/juin-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juin 2021 - LaMennais.org\" \/>\n<meta property=\"og:description\" content=\"MOIS DE JUIN Consacr\u00e9 au Coeur Sacr\u00e9 de J\u00e9sus Apostolat de la Pri\u00e8re, intention d\u2019\u00e9vang\u00e9lisation * * * * * * * * La beaut\u00e9 du mariage&nbsp;: Prions pour les jeunes qui se pr\u00e9parent au mariage avec le soutien d&#8217;une communaut\u00e9 chr\u00e9tienne : qu&#8217;ils grandissent dans l&#8217;amour, avec g\u00e9n\u00e9rosit\u00e9, fid\u00e9lit\u00e9 et patience. 1 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp; MARDI [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lamennais.org\/juin-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"LaMennais.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-02T11:37:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-08T11:47:43+00:00\" \/>\n<meta name=\"author\" content=\"Herv\u00e9 Asse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Herv\u00e9 Asse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/juin-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/juin-2021\\\/\"},\"author\":{\"name\":\"Herv\u00e9 Asse\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\"},\"headline\":\"Juin 2021\",\"datePublished\":\"2021-01-02T11:37:58+00:00\",\"dateModified\":\"2021-07-08T11:47:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/juin-2021\\\/\"},\"wordCount\":4902,\"articleSection\":[\"NOUVELLES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/juin-2021\\\/\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/juin-2021\\\/\",\"name\":\"Juin 2021 - LaMennais.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\"},\"datePublished\":\"2021-01-02T11:37:58+00:00\",\"dateModified\":\"2021-07-08T11:47:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/juin-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lamennais.org\\\/juin-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/juin-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lamennais.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juin 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/\",\"name\":\"LaMennais.org\",\"description\":\"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lamennais.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\",\"name\":\"Herv\u00e9 Asse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"caption\":\"Herv\u00e9 Asse\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juin 2021 - LaMennais.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lamennais.org\/juin-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Juin 2021 - LaMennais.org","og_description":"MOIS DE JUIN Consacr\u00e9 au Coeur Sacr\u00e9 de J\u00e9sus Apostolat de la Pri\u00e8re, intention d\u2019\u00e9vang\u00e9lisation * * * * * * * * La beaut\u00e9 du mariage&nbsp;: Prions pour les jeunes qui se pr\u00e9parent au mariage avec le soutien d&#8217;une communaut\u00e9 chr\u00e9tienne : qu&#8217;ils grandissent dans l&#8217;amour, avec g\u00e9n\u00e9rosit\u00e9, fid\u00e9lit\u00e9 et patience. 1 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp; MARDI [&hellip;]","og_url":"https:\/\/www.lamennais.org\/juin-2021\/","og_site_name":"LaMennais.org","article_published_time":"2021-01-02T11:37:58+00:00","article_modified_time":"2021-07-08T11:47:43+00:00","author":"Herv\u00e9 Asse","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Herv\u00e9 Asse","Tiempo de lectura":"24 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lamennais.org\/juin-2021\/#article","isPartOf":{"@id":"https:\/\/www.lamennais.org\/juin-2021\/"},"author":{"name":"Herv\u00e9 Asse","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844"},"headline":"Juin 2021","datePublished":"2021-01-02T11:37:58+00:00","dateModified":"2021-07-08T11:47:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lamennais.org\/juin-2021\/"},"wordCount":4902,"articleSection":["NOUVELLES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.lamennais.org\/juin-2021\/","url":"https:\/\/www.lamennais.org\/juin-2021\/","name":"Juin 2021 - LaMennais.org","isPartOf":{"@id":"https:\/\/www.lamennais.org\/#website"},"datePublished":"2021-01-02T11:37:58+00:00","dateModified":"2021-07-08T11:47:43+00:00","author":{"@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844"},"breadcrumb":{"@id":"https:\/\/www.lamennais.org\/juin-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lamennais.org\/juin-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lamennais.org\/juin-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lamennais.org\/"},{"@type":"ListItem","position":2,"name":"Juin 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.lamennais.org\/#website","url":"https:\/\/www.lamennais.org\/","name":"LaMennais.org","description":"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lamennais.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844","name":"Herv\u00e9 Asse","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","caption":"Herv\u00e9 Asse"}}]}},"_links":{"self":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/28415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/comments?post=28415"}],"version-history":[{"count":5,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/28415\/revisions"}],"predecessor-version":[{"id":30942,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/28415\/revisions\/30942"}],"wp:attachment":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/media?parent=28415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/categories?post=28415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/tags?post=28415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}