{"id":1913,"date":"2015-02-27T18:17:25","date_gmt":"2015-02-27T17:17:25","guid":{"rendered":"http:\/\/www.lamennais.org\/?p=1913"},"modified":"2017-10-24T09:28:04","modified_gmt":"2017-10-24T07:28:04","slug":"conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation","status":"publish","type":"post","link":"https:\/\/www.lamennais.org\/es\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/","title":{"rendered":"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire  de la congr\u00e9gation."},"content":{"rendered":"<p>Le Conseil g\u00e9n\u00e9ral\u00a0 est pr\u00e9sent jusqu&#8217;au 28 f\u00e9vrier \u00e0 la communaut\u00e9 des Fr\u00e8res de B\u00e9thanie \u00e0 Ciboure, France.<\/p>\n<p>De nombreux sujets sont partag\u00e9s lors de cette session, parmi ceux-ci s&#8217;inscrivent les premiers \u00e9l\u00e9ments de pr\u00e9paration du Bicentenaire de la fondation de la congr\u00e9gation en 2019. Une \u00e9quipe de Fr\u00e8res de France et d&#8217;Espagne s&#8217;est r\u00e9unie sur place \u00e0 l&#8217;invitation du Conseil\u00a0 le samedi 14 f\u00e9vrier. L&#8217;objectif \u00e9tait d&#8217;\u00e9changer sur les attentes, propositions, projets au service de l&#8217;ensemble de la congr\u00e9gation et de la Famille mennaisienne, en vue de la pr\u00e9paration du Bicentenaire.<\/p>\n<p>Une\u00a0 rencontre de pr\u00e9paration de l&#8217;Assembl\u00e9e internationale de la \u00ab\u00a0Famille Mennaisienne et Mission \u00e9ducative\u00a0\u00bb annonc\u00e9e en ao\u00fbt prochain \u00e0 Plo\u00ebrmel aura lieu \u00e9galement \u00e0 Ciboure le samedi 28.<\/p>\n<div style=\"width: 470px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/www.lamennais.org\/images\/images2015\/003_conseil01.jpg\" width=\"460\" height=\"345\" \/><p class=\"wp-caption-text\">Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation.<\/p><\/div>\n<p>&nbsp;<\/p>\n<div style=\"width: 470px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"http:\/\/www.lamennais.org\/images\/images2015\/003_conseil02.jpg\" width=\"460\" height=\"212\" \/><p class=\"wp-caption-text\">Les Fr\u00e8res du Conseil g\u00e9n\u00e9ral sont accueillis \u00e0 la communaut\u00e9 de B\u00e9thanie \u00e0 Ciboure.<\/p><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil g\u00e9n\u00e9ral\u00a0 est pr\u00e9sent jusqu&#8217;au 28 f\u00e9vrier \u00e0 la communaut\u00e9 des Fr\u00e8res de B\u00e9thanie \u00e0 Ciboure, France. De nombreux sujets sont partag\u00e9s lors de cette session, parmi ceux-ci s&#8217;inscrivent les premiers \u00e9l\u00e9ments de pr\u00e9paration du Bicentenaire de la fondation de la congr\u00e9gation en 2019. Une \u00e9quipe de Fr\u00e8res de France et d&#8217;Espagne s&#8217;est r\u00e9unie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[333],"tags":[],"class_list":["post-1913","post","type-post","status-publish","format-standard","hentry","category-archives"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation. - LaMennais.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation. - LaMennais.org\" \/>\n<meta property=\"og:description\" content=\"Le Conseil g\u00e9n\u00e9ral\u00a0 est pr\u00e9sent jusqu&#8217;au 28 f\u00e9vrier \u00e0 la communaut\u00e9 des Fr\u00e8res de B\u00e9thanie \u00e0 Ciboure, France. De nombreux sujets sont partag\u00e9s lors de cette session, parmi ceux-ci s&#8217;inscrivent les premiers \u00e9l\u00e9ments de pr\u00e9paration du Bicentenaire de la fondation de la congr\u00e9gation en 2019. Une \u00e9quipe de Fr\u00e8res de France et d&#8217;Espagne s&#8217;est r\u00e9unie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es\" \/>\n<meta property=\"og:site_name\" content=\"LaMennais.org\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-27T17:17:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-24T07:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.lamennais.org\/images\/images2015\/003_conseil01.jpg\" \/>\n<meta name=\"author\" content=\"admon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es\"},\"author\":{\"name\":\"admon\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/a0284cbd3544e52f538d69e4acf1e58a\"},\"headline\":\"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation.\",\"datePublished\":\"2015-02-27T17:17:25+00:00\",\"dateModified\":\"2017-10-24T07:28:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es\"},\"wordCount\":207,\"image\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.lamennais.org\\\/images\\\/images2015\\\/003_conseil01.jpg\",\"articleSection\":[\"Archives\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es\",\"name\":\"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation. - LaMennais.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.lamennais.org\\\/images\\\/images2015\\\/003_conseil01.jpg\",\"datePublished\":\"2015-02-27T17:17:25+00:00\",\"dateModified\":\"2017-10-24T07:28:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/a0284cbd3544e52f538d69e4acf1e58a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es#primaryimage\",\"url\":\"http:\\\/\\\/www.lamennais.org\\\/images\\\/images2015\\\/003_conseil01.jpg\",\"contentUrl\":\"http:\\\/\\\/www.lamennais.org\\\/images\\\/images2015\\\/003_conseil01.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\\\/?lang=es#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lamennais.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/\",\"name\":\"LaMennais.org\",\"description\":\"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lamennais.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/a0284cbd3544e52f538d69e4acf1e58a\",\"name\":\"admon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g\",\"caption\":\"admon\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation. - LaMennais.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es","og_locale":"es_ES","og_type":"article","og_title":"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation. - LaMennais.org","og_description":"Le Conseil g\u00e9n\u00e9ral\u00a0 est pr\u00e9sent jusqu&#8217;au 28 f\u00e9vrier \u00e0 la communaut\u00e9 des Fr\u00e8res de B\u00e9thanie \u00e0 Ciboure, France. De nombreux sujets sont partag\u00e9s lors de cette session, parmi ceux-ci s&#8217;inscrivent les premiers \u00e9l\u00e9ments de pr\u00e9paration du Bicentenaire de la fondation de la congr\u00e9gation en 2019. Une \u00e9quipe de Fr\u00e8res de France et d&#8217;Espagne s&#8217;est r\u00e9unie [&hellip;]","og_url":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es","og_site_name":"LaMennais.org","article_published_time":"2015-02-27T17:17:25+00:00","article_modified_time":"2017-10-24T07:28:04+00:00","og_image":[{"url":"http:\/\/www.lamennais.org\/images\/images2015\/003_conseil01.jpg","type":"","width":"","height":""}],"author":"admon","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admon","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es#article","isPartOf":{"@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es"},"author":{"name":"admon","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/a0284cbd3544e52f538d69e4acf1e58a"},"headline":"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation.","datePublished":"2015-02-27T17:17:25+00:00","dateModified":"2017-10-24T07:28:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es"},"wordCount":207,"image":{"@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es#primaryimage"},"thumbnailUrl":"http:\/\/www.lamennais.org\/images\/images2015\/003_conseil01.jpg","articleSection":["Archives"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es","url":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es","name":"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation. - LaMennais.org","isPartOf":{"@id":"https:\/\/www.lamennais.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es#primaryimage"},"image":{"@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es#primaryimage"},"thumbnailUrl":"http:\/\/www.lamennais.org\/images\/images2015\/003_conseil01.jpg","datePublished":"2015-02-27T17:17:25+00:00","dateModified":"2017-10-24T07:28:04+00:00","author":{"@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/a0284cbd3544e52f538d69e4acf1e58a"},"breadcrumb":{"@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es#primaryimage","url":"http:\/\/www.lamennais.org\/images\/images2015\/003_conseil01.jpg","contentUrl":"http:\/\/www.lamennais.org\/images\/images2015\/003_conseil01.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lamennais.org\/conseil-general-session-a-ciboure-francepremieres-reflexions-au-sujet-de-la-preparation-du-bicentenaire-de-la-congregation\/?lang=es#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lamennais.org\/"},{"@type":"ListItem","position":2,"name":"CONSEIL GENERAL. Session \u00e0 Ciboure, France Premi\u00e8res r\u00e9flexions au sujet de la pr\u00e9paration du Bicentenaire de la congr\u00e9gation."}]},{"@type":"WebSite","@id":"https:\/\/www.lamennais.org\/#website","url":"https:\/\/www.lamennais.org\/","name":"LaMennais.org","description":"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lamennais.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/a0284cbd3544e52f538d69e4acf1e58a","name":"admon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e69e6842b80ff10350a4c83f8c2e6ed6596fd887741cad3e5032828126fba0f2?s=96&d=mm&r=g","caption":"admon"}}]}},"_links":{"self":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/1913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/comments?post=1913"}],"version-history":[{"count":4,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/1913\/revisions"}],"predecessor-version":[{"id":3957,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/1913\/revisions\/3957"}],"wp:attachment":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/media?parent=1913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/categories?post=1913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/tags?post=1913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}