{"id":10330,"date":"2017-01-11T09:40:10","date_gmt":"2017-01-11T08:40:10","guid":{"rendered":"http:\/\/www.lamennais.org\/?p=10330"},"modified":"2017-01-11T17:04:27","modified_gmt":"2017-01-11T16:04:27","slug":"votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo","status":"publish","type":"post","link":"https:\/\/www.lamennais.org\/es\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/","title":{"rendered":"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo."},"content":{"rendered":"<p>Foto arriba :\u00a0<em>De izquierda a derecha: el concelebrante, el Hno. Gilles MBOLIHINIE, nuevo profeso, Mons. Richard DOMBA, Obispo de Dungu-Doruma, el Hno Guillermo D\u00c1VILA, Asistente, y el Hno. Pascual MBOLINGABA, Visitador del distrito.<\/em><\/p>\n<div id=\"attachment_10249\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-10249\" class=\"wp-image-10249 size-medium\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4549-300x191.jpg\" width=\"300\" height=\"191\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4549-300x191.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4549-768x488.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4549-1024x651.jpg 1024w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4549-260x165.jpg 260w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-10249\" class=\"wp-caption-text\"><em>Los Hermanos del Congo RDC que asistieron a la ceremonia.<\/em><\/p><\/div>\n<p>\u00a1Fiesta en Dungu, en el Congo RDC, el domingo, 8 de enero! El Distrito San Juan Pablo II (Congo-Ruanda) vivi\u00f3 la profesi\u00f3n perpetua del Hermano Gilles MBOLIHINIE, de 27 a\u00f1os de edad.<\/p>\n<div id=\"attachment_10255\" style=\"width: 310px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-10255\" class=\"wp-image-10255 size-medium\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01866-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01866-300x225.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01866-768x576.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01866-1024x768.jpg 1024w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01866-260x195.jpg 260w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-10255\" class=\"wp-caption-text\"><em>La familia del Hno. Gilles. A la derecha el Hno Pascal Mbolingaba, Visitador.<\/em><\/p><\/div>\n<p>La ceremonia fue presidida por Mons. Richard DOMBA, Obispo de Dungu-Doruma, en su catedral. Recibi\u00f3 los votos el Hno. Guillermo D\u00c1VILA, Asistente, con asistencia tambi\u00e9n del Hno. Pascual MBOLINGABA, Visitador del Distrito.<br \/>\nDespu\u00e9s de una misa muy animada por el pueblo con una multitud de j\u00f3venes y ni\u00f1os, el Hermano Gilles, su familia y los Hermanos continuaron este gran momento de alegr\u00eda con una comida festiva.<\/p>\n<p><img decoding=\"async\" class=\"alignleft size-medium wp-image-10246\" src=\"http:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01823-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01823-300x187.jpg 300w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01823-768x479.jpg 768w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01823-1024x639.jpg 1024w, https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/DSC01823-260x162.jpg 260w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto arriba :\u00a0De izquierda a derecha: el concelebrante, el Hno. Gilles MBOLIHINIE, nuevo profeso, Mons. Richard DOMBA, Obispo de Dungu-Doruma, el Hno Guillermo D\u00c1VILA, Asistente, y el Hno. Pascual MBOLINGABA, Visitador del distrito. \u00a1Fiesta en Dungu, en el Congo RDC, el domingo, 8 de enero! El Distrito San Juan Pablo II (Congo-Ruanda) vivi\u00f3 la profesi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10265,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,161,222],"tags":[],"class_list":["post-10330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-noticias-hermanos","category-noticias-iglesia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo. - LaMennais.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo. - LaMennais.org\" \/>\n<meta property=\"og:description\" content=\"Foto arriba :\u00a0De izquierda a derecha: el concelebrante, el Hno. Gilles MBOLIHINIE, nuevo profeso, Mons. Richard DOMBA, Obispo de Dungu-Doruma, el Hno Guillermo D\u00c1VILA, Asistente, y el Hno. Pascual MBOLINGABA, Visitador del distrito. \u00a1Fiesta en Dungu, en el Congo RDC, el domingo, 8 de enero! El Distrito San Juan Pablo II (Congo-Ruanda) vivi\u00f3 la profesi\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es\" \/>\n<meta property=\"og:site_name\" content=\"LaMennais.org\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-11T08:40:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-11T16:04:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4562-1-1024x724.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Herv\u00e9 Asse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Herv\u00e9 Asse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es\"},\"author\":{\"name\":\"Herv\u00e9 Asse\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\"},\"headline\":\"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo.\",\"datePublished\":\"2017-01-11T08:40:10+00:00\",\"dateModified\":\"2017-01-11T16:04:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es\"},\"wordCount\":187,\"image\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/SAM_4562-1.jpg\",\"articleSection\":[\"NOTICIAS\",\"Noticias - Hermanos\",\"Noticias - Iglesia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es\",\"name\":\"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo. - LaMennais.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/SAM_4562-1.jpg\",\"datePublished\":\"2017-01-11T08:40:10+00:00\",\"dateModified\":\"2017-01-11T16:04:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es#primaryimage\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/SAM_4562-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lamennais.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/SAM_4562-1.jpg\",\"width\":3258,\"height\":2304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\\\/?lang=es#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lamennais.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#website\",\"url\":\"https:\\\/\\\/www.lamennais.org\\\/\",\"name\":\"LaMennais.org\",\"description\":\"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lamennais.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lamennais.org\\\/#\\\/schema\\\/person\\\/2a8d6e8a95babedd5ba1c43afd2e3844\",\"name\":\"Herv\u00e9 Asse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g\",\"caption\":\"Herv\u00e9 Asse\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo. - LaMennais.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es","og_locale":"es_ES","og_type":"article","og_title":"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo. - LaMennais.org","og_description":"Foto arriba :\u00a0De izquierda a derecha: el concelebrante, el Hno. Gilles MBOLIHINIE, nuevo profeso, Mons. Richard DOMBA, Obispo de Dungu-Doruma, el Hno Guillermo D\u00c1VILA, Asistente, y el Hno. Pascual MBOLINGABA, Visitador del distrito. \u00a1Fiesta en Dungu, en el Congo RDC, el domingo, 8 de enero! El Distrito San Juan Pablo II (Congo-Ruanda) vivi\u00f3 la profesi\u00f3n [&hellip;]","og_url":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es","og_site_name":"LaMennais.org","article_published_time":"2017-01-11T08:40:10+00:00","article_modified_time":"2017-01-11T16:04:27+00:00","og_image":[{"width":1024,"height":724,"url":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4562-1-1024x724.jpg","type":"image\/jpeg"}],"author":"Herv\u00e9 Asse","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Herv\u00e9 Asse","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es#article","isPartOf":{"@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es"},"author":{"name":"Herv\u00e9 Asse","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844"},"headline":"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo.","datePublished":"2017-01-11T08:40:10+00:00","dateModified":"2017-01-11T16:04:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es"},"wordCount":187,"image":{"@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es#primaryimage"},"thumbnailUrl":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4562-1.jpg","articleSection":["NOTICIAS","Noticias - Hermanos","Noticias - Iglesia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es","url":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es","name":"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo. - LaMennais.org","isPartOf":{"@id":"https:\/\/www.lamennais.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es#primaryimage"},"image":{"@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es#primaryimage"},"thumbnailUrl":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4562-1.jpg","datePublished":"2017-01-11T08:40:10+00:00","dateModified":"2017-01-11T16:04:27+00:00","author":{"@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844"},"breadcrumb":{"@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es#primaryimage","url":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4562-1.jpg","contentUrl":"https:\/\/www.lamennais.org\/wp-content\/uploads\/2017\/01\/SAM_4562-1.jpg","width":3258,"height":2304},{"@type":"BreadcrumbList","@id":"https:\/\/www.lamennais.org\/votos-profesion-del-hno-gilles-mbolihinie-en-dungu-rdc-del-congo\/?lang=es#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lamennais.org\/"},{"@type":"ListItem","position":2,"name":"VOTOS. Profesi\u00f3n del Hno. Gilles MBOLIHINIE, en Dungu, RDC del Congo."}]},{"@type":"WebSite","@id":"https:\/\/www.lamennais.org\/#website","url":"https:\/\/www.lamennais.org\/","name":"LaMennais.org","description":"Fr\u00e8res de l&#039;Instruction Chr\u00e9tienne et Famille Mennaisienne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lamennais.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lamennais.org\/#\/schema\/person\/2a8d6e8a95babedd5ba1c43afd2e3844","name":"Herv\u00e9 Asse","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aaa7b1baf759c8b40525f40af381cbaa2b0ddd554f57145bceb0654ba45b4c0?s=96&d=mm&r=g","caption":"Herv\u00e9 Asse"}}]}},"_links":{"self":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/10330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/comments?post=10330"}],"version-history":[{"count":1,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/10330\/revisions"}],"predecessor-version":[{"id":10331,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/posts\/10330\/revisions\/10331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/media\/10265"}],"wp:attachment":[{"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/media?parent=10330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/categories?post=10330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lamennais.org\/es\/wp-json\/wp\/v2\/tags?post=10330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}